{"id":9633,"date":"2014-10-20T12:24:44","date_gmt":"2014-10-20T16:24:44","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=9633"},"modified":"2014-10-20T12:24:44","modified_gmt":"2014-10-20T16:24:44","slug":"dr-ivan-rivera-toma-posesion-de-la-gobernacion-de-puerto-plata","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/dr-ivan-rivera-toma-posesion-de-la-gobernacion-de-puerto-plata\/","title":{"rendered":"Dr. Ivan Rivera toma posesi\u00f3n de la Gobernaci\u00f3n de Puerto Plata"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/0_a_ivan-rivera-_210_120.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9634 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/0_a_ivan-rivera-_210_120.jpg\" alt=\"0_a_ivan-rivera-_210_120\" width=\"210\" height=\"120\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/0_a_ivan-rivera-_210_120.jpg 210w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/0_a_ivan-rivera-_210_120-595x340.jpg 595w\" sizes=\"auto, (max-width: 210px) 100vw, 210px\" \/><\/a>PUERTO PLATA.- En un acto muy concurrido, celebrado en el sal\u00f3n de conferencias del la Gobernaci\u00f3n Provincial de Puerto Plata, el Doctor Ivan Rivera tom\u00f3 posesi\u00f3n, como nuevo gobernador de esta provincia.<!--more--><\/p>\n<p>Ivan Rivera, sustituy\u00f3 a su compa\u00f1era del Partido de la Liberacion Dominicana, Eridania Llibre, quien se hab\u00eda despe\u00f1ado en el cargo desde el a\u00f1o 2008, cuando fue designada en la posici\u00f3n, por el entonces presidente, Doctor Leonel Fern\u00e1ndez Reina.<\/p>\n<p>Rivera quien se dirigi\u00f3 a los presentes, llam\u00f3 a los Puertoplate\u00f1os a unificar esfuerzos para lograr el desarrollo, de la provincia, sin importar bander\u00eda pol\u00edtica ni clase social a la que pertenezcan. \u201cUstedes y nosotros debemos ser indesligables, el punto m\u00e1s importante, la unidad, sigan siendo opositores, gremialistas, asociados a cualquier organizaci\u00f3n, pero jam\u00e1s dejen de ser unitarios para el desarrollo de Puerto Plata, que todos los temas terminen con un criterio unificado en una sola direcci\u00f3n para que tenga fuerza la contribuci\u00f3n a los mejores intereses de la provincia\u201d dijo el nuevo Gobernador de Puerto Plata.<\/p>\n<p>Durante el acto, Ivan Rivera, estuvo acompa\u00f1ado por familiares, amigos y compa\u00f1eros de partido, a quienes agradeci\u00f3 el apoyo brindado durante toda su carrera pol\u00edtica, la cual siempre ha estado ligada al Partido de la Liberaci\u00f3n Dominicana, al Profesor Juan Bosh, pero sobre todo al actual presidente de la Rep\u00fablica, Danilo Medina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PUERTO PLATA.- En un acto muy concurrido, celebrado en el sal\u00f3n de conferencias del la Gobernaci\u00f3n Provincial de Puerto Plata, el Doctor Ivan Rivera tom\u00f3 posesi\u00f3n, como nuevo gobernador de esta provincia.<\/p>\n","protected":false},"author":3,"featured_media":9634,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-9633","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/9633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=9633"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/9633\/revisions"}],"predecessor-version":[{"id":9635,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/9633\/revisions\/9635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/9634"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=9633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=9633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=9633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}