{"id":96385,"date":"2024-05-17T18:36:49","date_gmt":"2024-05-17T22:36:49","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=96385"},"modified":"2024-05-17T18:37:04","modified_gmt":"2024-05-17T22:37:04","slug":"interesados-en-el-concurso-de-oposicion-docente-tienen-hasta-el-26-de-mayo-para-inscribirse","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/interesados-en-el-concurso-de-oposicion-docente-tienen-hasta-el-26-de-mayo-para-inscribirse\/","title":{"rendered":"Interesados en el Concurso de Oposici\u00f3n Docente tienen hasta el 26 de mayo para inscribirse"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/05\/minerd-convoca-al-concurso-docente-para-cubrir-8-mil-vacantes_2-focus-0-0-896-504.jpg\" alt=\"\" class=\"wp-image-96386\" width=\"235\" height=\"131\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/05\/minerd-convoca-al-concurso-docente-para-cubrir-8-mil-vacantes_2-focus-0-0-896-504.jpg 896w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/05\/minerd-convoca-al-concurso-docente-para-cubrir-8-mil-vacantes_2-focus-0-0-896-504-300x169.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/05\/minerd-convoca-al-concurso-docente-para-cubrir-8-mil-vacantes_2-focus-0-0-896-504-768x432.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/05\/minerd-convoca-al-concurso-docente-para-cubrir-8-mil-vacantes_2-focus-0-0-896-504-600x338.jpg 600w\" sizes=\"auto, (max-width: 235px) 100vw, 235px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Los interesados en participar en el&nbsp;<strong>Concurso<\/strong>&nbsp;de&nbsp;<strong>Oposici\u00f3n<\/strong>&nbsp;<strong>Docente<\/strong>&nbsp;Focalizado 2024 tienen hasta el domingo 26 de este mes de mayo para registrarse e inscribirse en el&nbsp;<strong>proceso<\/strong>&nbsp;que procura cubrir&nbsp;<strong>plazas<\/strong>&nbsp;vacantes en las 18 Direcciones<strong>&nbsp;Regionales<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La&nbsp;<strong>Comisi\u00f3n<\/strong>&nbsp;Nacional del&nbsp;<strong>Concurso<\/strong>&nbsp;de&nbsp;<strong>Oposici\u00f3n<\/strong>&nbsp;<strong>Docente<\/strong>, integrada por el&nbsp;<strong>Ministerio<\/strong>&nbsp;de&nbsp;<strong>Educaci\u00f3n<\/strong>&nbsp;de la Rep\u00fablica Dominicana (<strong>Minerd<\/strong>), la Asociaci\u00f3n Dominicana de Profesores (<strong>ADP<\/strong>) y el&nbsp;<strong>Ministerio<\/strong>&nbsp;de Administraci\u00f3n P\u00fablica (<strong>MAP<\/strong>), hizo el anuncio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En una nota de prensa, explic\u00f3 que para participar en el\u00a0<strong>proceso<\/strong>\u00a0de manera adecuada, el postulante debe leer el contenido de la Orden Departamental 16\/2024, las gu\u00edas y protocolos publicados en la plataforma de la instituci\u00f3n educativa, as\u00ed como cargar su\u00a0<strong>expediente<\/strong>, seg\u00fan lo indicado en los\u00a0<strong>art\u00edculos<\/strong>\u00a016 y 17 de la referida disposici\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La comisi\u00f3n enfatiz\u00f3 que los&nbsp;<strong>postulantes<\/strong>&nbsp;deben de presentarse en todas las&nbsp;<strong>etapas<\/strong>&nbsp;del&nbsp;<strong>Concurso<\/strong>: de Registro e Inscripci\u00f3n, de Pruebas (Habilidades cognitivas generales y de conocimientos disciplinares y pedag\u00f3gicos), y en la etapa de Entrevista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las entidades que conforman la&nbsp;<strong>Comisi\u00f3n<\/strong>&nbsp;Nacional del&nbsp;<strong>Concurso<\/strong>&nbsp;de&nbsp;<strong>Oposici\u00f3n<\/strong>&nbsp;<strong>Docente<\/strong>&nbsp;hicieron un llamado a los&nbsp;<strong>postulantes<\/strong>&nbsp;para que sigan fielmente la Orden Departamental 16\/2024, que es la que establece todas las&nbsp;<strong>normas<\/strong>&nbsp;de la&nbsp;<strong>convocatoria<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abQueremos dejar claro que el&nbsp;<strong>Ministerio<\/strong>&nbsp;de&nbsp;<strong>Educaci\u00f3n<\/strong>&nbsp;no ha autorizado la realizaci\u00f3n de cursos o talleres en ninguna zona geogr\u00e1fica del pa\u00eds como parte de este&nbsp;<strong>proceso<\/strong>. Por lo tanto, nos desvinculamos de cualquier&nbsp;<strong>individuo<\/strong>&nbsp;u&nbsp;<strong>organizaci\u00f3n<\/strong>&nbsp;que promueva este tipo de actividades\u00bb, puntualiz\u00f3 la&nbsp;<strong>Comisi\u00f3n<\/strong>&nbsp;Nacional del&nbsp;<strong>Concurso<\/strong>, a trav\u00e9s de la nota de prensa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La comisi\u00f3n reiter\u00f3 que \u00abes esencial\u00bb que todos los&nbsp;<strong>postulantes<\/strong>&nbsp;sigan las instrucciones, \u00fanicamente, a trav\u00e9s de los canales oficiales de&nbsp;<strong>comunicaci\u00f3n<\/strong>&nbsp;del&nbsp;<strong>Minerd<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los interesados en participar en el&nbsp;Concurso&nbsp;de&nbsp;Oposici\u00f3n&nbsp;Docente&nbsp;Focalizado 2024 tienen hasta el domingo 26 de este mes de mayo para registrarse e inscribirse en el&nbsp;proceso&nbsp;que procura cubrir&nbsp;plazas&nbsp;vacantes en las 18 Direcciones&nbsp;Regionales.&nbsp; La&nbsp;Comisi\u00f3n&nbsp;Nacional del&nbsp;Concurso&nbsp;de&nbsp;Oposici\u00f3n&nbsp;Docente, integrada por el&nbsp;Ministerio&nbsp;de&nbsp;Educaci\u00f3n&nbsp;de la Rep\u00fablica Dominicana (Minerd), la Asociaci\u00f3n Dominicana de Profesores (ADP) y el&nbsp;Ministerio&nbsp;de Administraci\u00f3n P\u00fablica (MAP), hizo el anuncio. En una nota de prensa, explic\u00f3 que para participar en el\u00a0proceso\u00a0de manera adecuada, el postulante debe leer el contenido de la Orden Departamental 16\/2024, las gu\u00edas y protocolos publicados en la plataforma de la instituci\u00f3n educativa, as\u00ed como cargar su\u00a0expediente, seg\u00fan lo indicado en los\u00a0art\u00edculos\u00a016 y 17 de la referida disposici\u00f3n. La comisi\u00f3n enfatiz\u00f3 que los&nbsp;postulantes&nbsp;deben de presentarse en todas las&nbsp;etapas&nbsp;del&nbsp;Concurso: de Registro e Inscripci\u00f3n, de Pruebas (Habilidades cognitivas generales y de conocimientos disciplinares y pedag\u00f3gicos), y en la etapa de Entrevista. Las entidades que conforman la&nbsp;Comisi\u00f3n&nbsp;Nacional del&nbsp;Concurso&nbsp;de&nbsp;Oposici\u00f3n&nbsp;Docente&nbsp;hicieron un llamado a los&nbsp;postulantes&nbsp;para que sigan fielmente la Orden Departamental 16\/2024, que es la que establece todas las&nbsp;normas&nbsp;de la&nbsp;convocatoria.&nbsp; \u00abQueremos dejar claro que el&nbsp;Ministerio&nbsp;de&nbsp;Educaci\u00f3n&nbsp;no ha autorizado la realizaci\u00f3n de cursos o talleres en ninguna zona geogr\u00e1fica del pa\u00eds como parte de este&nbsp;proceso. Por lo tanto, nos desvinculamos de cualquier&nbsp;individuo&nbsp;u&nbsp;organizaci\u00f3n&nbsp;que promueva este tipo de actividades\u00bb, puntualiz\u00f3 la&nbsp;Comisi\u00f3n&nbsp;Nacional del&nbsp;Concurso, a trav\u00e9s de la nota de prensa. La comisi\u00f3n reiter\u00f3 que \u00abes esencial\u00bb que todos los&nbsp;postulantes&nbsp;sigan las instrucciones, \u00fanicamente, a trav\u00e9s de los canales oficiales de&nbsp;comunicaci\u00f3n&nbsp;del&nbsp;Minerd.<\/p>\n","protected":false},"author":9,"featured_media":96386,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[459],"tags":[],"class_list":["post-96385","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=96385"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96385\/revisions"}],"predecessor-version":[{"id":96387,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96385\/revisions\/96387"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/96386"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=96385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=96385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=96385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}