{"id":96532,"date":"2024-05-28T08:05:54","date_gmt":"2024-05-28T12:05:54","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=96532"},"modified":"2024-05-28T08:05:55","modified_gmt":"2024-05-28T12:05:55","slug":"presidente-dominicano-viajo-a-portugal-concluyo-visita-a-italia","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/presidente-dominicano-viajo-a-portugal-concluyo-visita-a-italia\/","title":{"rendered":"Presidente dominicano viaj\u00f3 a Portugal; concluy\u00f3 visita a Italia"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/05\/d557e866-c01e-4302-b760-4f2bedb5965a-1024x682.jpeg\" alt=\"\" class=\"wp-image-96533\" width=\"253\" height=\"168\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/05\/d557e866-c01e-4302-b760-4f2bedb5965a-1024x682.jpeg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/05\/d557e866-c01e-4302-b760-4f2bedb5965a-300x200.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/05\/d557e866-c01e-4302-b760-4f2bedb5965a-768x512.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/05\/d557e866-c01e-4302-b760-4f2bedb5965a-600x400.jpeg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/05\/d557e866-c01e-4302-b760-4f2bedb5965a.jpeg 1280w\" sizes=\"auto, (max-width: 253px) 100vw, 253px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Santo Domingo, 27 may (Prensa Latina) El presidente dominicano, Luis Abinader, viaj\u00f3 hoy a Portugal tras concluir una visita de tres d\u00edas a Italia, donde fue recibido por el papa Francisco, inform\u00f3 la direcci\u00f3n de prensa presidencial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Portugal el mandatario se reunir\u00e1 con su hom\u00f3logo, Marcelo Rebelo de Sousa, en el Palacio de Bel\u00e9m.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A su llegada a ese pa\u00eds, ser\u00e1 recibido por el jefe de Protocolo del Estado Portugu\u00e9s, Jorge Silva, el embajador Miguel Prestol y el comandante de la base militar, Abel Oliveira, seg\u00fan la misma fuente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antes de trasladarse a Lisboa la noche del lunes (en Italia), Abinader se reuni\u00f3 con su par Sergio Mattarella, ocasi\u00f3n en la que dialogaron sobre temas de inter\u00e9s para las dos naciones, como el fortalecimiento del turismo y el intercambio comercial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este lunes el jefe de Estado caribe\u00f1o fue recibido por el papa Francisco, quien lo felicit\u00f3 por su reelecci\u00f3n en los comicios del 19 de mayo \u00faltimo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante una audiencia privada en la Ciudad del Vaticano, que se extendi\u00f3 unos 30 minutos, el sumo pont\u00edfice le manifest\u00f3 su inter\u00e9s en visitar esta naci\u00f3n caribe\u00f1a, luego de una invitaci\u00f3n formal que le hiciera el gobernante, indic\u00f3 la direcci\u00f3n de prensa del Presidente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con posterioridad Abinader se reuni\u00f3 con el secretario de Estado de la Santa Sede, Pietro Parolin, comunic\u00f3 el sitio de la Presidencia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo, 27 may (Prensa Latina) El presidente dominicano, Luis Abinader, viaj\u00f3 hoy a Portugal tras concluir una visita de tres d\u00edas a Italia, donde fue recibido por el papa Francisco, inform\u00f3 la direcci\u00f3n de prensa presidencial. En Portugal el mandatario se reunir\u00e1 con su hom\u00f3logo, Marcelo Rebelo de Sousa, en el Palacio de Bel\u00e9m. A su llegada a ese pa\u00eds, ser\u00e1 recibido por el jefe de Protocolo del Estado Portugu\u00e9s, Jorge Silva, el embajador Miguel Prestol y el comandante de la base militar, Abel Oliveira, seg\u00fan la misma fuente. Antes de trasladarse a Lisboa la noche del lunes (en Italia), Abinader se reuni\u00f3 con su par Sergio Mattarella, ocasi\u00f3n en la que dialogaron sobre temas de inter\u00e9s para las dos naciones, como el fortalecimiento del turismo y el intercambio comercial. Este lunes el jefe de Estado caribe\u00f1o fue recibido por el papa Francisco, quien lo felicit\u00f3 por su reelecci\u00f3n en los comicios del 19 de mayo \u00faltimo. Durante una audiencia privada en la Ciudad del Vaticano, que se extendi\u00f3 unos 30 minutos, el sumo pont\u00edfice le manifest\u00f3 su inter\u00e9s en visitar esta naci\u00f3n caribe\u00f1a, luego de una invitaci\u00f3n formal que le hiciera el gobernante, indic\u00f3 la direcci\u00f3n de prensa del Presidente. Con posterioridad Abinader se reuni\u00f3 con el secretario de Estado de la Santa Sede, Pietro Parolin, comunic\u00f3 el sitio de la Presidencia.<\/p>\n","protected":false},"author":9,"featured_media":96533,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-96532","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=96532"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96532\/revisions"}],"predecessor-version":[{"id":96534,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96532\/revisions\/96534"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/96533"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=96532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=96532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=96532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}