{"id":96865,"date":"2024-06-17T07:59:52","date_gmt":"2024-06-17T11:59:52","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=96865"},"modified":"2024-06-17T07:59:53","modified_gmt":"2024-06-17T11:59:53","slug":"carlos-adames-retiene-titulo-cmb-alberto-puello-gana-el-superligero","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/carlos-adames-retiene-titulo-cmb-alberto-puello-gana-el-superligero\/","title":{"rendered":"Carlos Adames retiene t\u00edtulo CMB; Alberto Puello gana el superligero"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/BRONCO-1.jpg\" alt=\"\" class=\"wp-image-96866\" width=\"239\" height=\"138\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/BRONCO-1.jpg 553w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/BRONCO-1-300x174.jpg 300w\" sizes=\"auto, (max-width: 239px) 100vw, 239px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">NEVADA.- El peleador dominicano Carlos Adames derrot\u00f3 de manera un\u00e1nime al estadounidense Terrell Gausha para retener el t\u00edtulo de peso mediano del Consejo Mundial de Boxeo (CMB) en el MGM Grand Garden Arena de Las Vegas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su&nbsp;primera defensa, despu\u00e9s de ser ascendido de campe\u00f3n interino a monarca absoluto, Adames solvent\u00f3 la oposici\u00f3n del ol\u00edmpico estadounidense, aunque no pudo noquearlo.&nbsp;Dos jueces votaron id\u00e9ntico 119-109 y el tercero 118-110, todos a favor del quisqueyano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEsta fue una victoria muy satisfactoria, habiendo defendido mi titulo de la manera que lo hice con una decisi\u00f3n contundente. Era lo que quer\u00eda tras haber pasado un a\u00f1o sin pelear, dijo Adames.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue un combate de pocos golpes y seg\u00fan el conteo de&nbsp;Compubox, ambos peleadores aterrizaron 107 golpes y lanzaron la misma cantidad de golpes de poder: 200.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La pelea fue m\u00e1s pareja de lo que reflejaron las tarjetas de los imparciales. Adames tom\u00f3 la iniciativa e impuso el ritmo con combinaciones de golpes a la cabeza y las zonas blandas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl nocaut estaba latente hasta que conect\u00e9 ese golpe bajo sin querer. Fue desafortunado. (Gausha) se pudo recomponer y tomar aire despu\u00e9s de eso. Supo ser un rival inc\u00f3modo para m\u00ed\u201d, agreg\u00f3 el dominicano en la conferencia de prensa. \u201c\u00a1Lo mejor est\u00e1 por venir! Quiero darle las gracias a la gente por haber venido a apoyarme\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gausha por momentos se meti\u00f3 en el combate, pero el exceso de cautela le pas\u00f3 factura ante el ojo de los jueces.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCarlos Adames es un gran boxeador con una pegada potente, as\u00ed que yo sab\u00eda que deb\u00eda ser cauteloso en los rounds iniciales. Mi estrategia era ser m\u00e1s agresivo en los asaltos finales, y yo pens\u00e9 que lo hab\u00eda sido, pero eso obviamente no alcanz\u00f3 esta noche\u201d, coment\u00f3 Gausha. \u201cEl margen de las tarjetas fue amplio y no estuve de acuerdo con ellas. Pens\u00e9 que hab\u00eda sido una pelea m\u00e1s re\u00f1ida, pero al final \u00e9l gan\u00f3 la pelea y no se puede hacer nada al respecto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la victoria, el peleador dominicano de 30 a\u00f1os mejor\u00f3 su r\u00e9cord a 24-1-0, 18 KO\u2019s. En tanto, Gausha, de 36, dej\u00f3 su balance profesional en 24-4-1, 12 KO\u2019s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstoy bendecido por hacer lo que amo a los 36 a\u00f1os de edad sin lesiones y una gran capacidad defensiva. Simplemente debo volver al pizarr\u00f3n y ya veremos que haremos\u201d, concluy\u00f3 el pugilista estadounidense que fall\u00f3 por tercera ocasi\u00f3n en una oportunidad titular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Puello sorprende y derrota a Gary Antuanne Russell<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alberto Puello&nbsp;complet\u00f3 la fiesta para la Rep\u00fablica Dominicana al superar contra todo pron\u00f3stico al hasta entonces invicto estadounidense&nbsp;Gary Antuanne Russell&nbsp;y as\u00ed agenciarse el&nbsp;t\u00edtulo interino superligero del CMB.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La victoria de Puello lleg\u00f3 por decisi\u00f3n dividida.&nbsp;Un juez vot\u00f3 118-109 para Rusell, pero los otros le dieron el veredicto al dominicano 115-112 y 114-113.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCuando celebr\u00e9 cayendo de rodillas al suelo, lo primero que hice fue darle las gracias a Dios, y luego dije \u2018lo logr\u00e9\u2019. La barrera del peso y el tiempo pasado lejos de mi familia valieron la pena despu\u00e9s de todo\u201d, dijo despu\u00e9s del combate el peleador de 29 a\u00f1os de San Juan de la Maguana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La precisi\u00f3n en el contragolpe de \u2018La Avispa\u2019 Puello hizo la diferencia, a pesar de que le quitaron un punto en el round 9 por aguantar. De acuerdo con Compubox, tuvo una efectividad del 26.6% (aterriz\u00f3 112 de 425 golpes lanzados, superior al 16.2% (100 de 619) de Russell.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl ser campe\u00f3n se siente fenomenal, ya que este momento marca un antes y un despu\u00e9s en mi carrera y en mi vida\u201d, indic\u00f3 Puello que mejor\u00f3 su r\u00e9cord a 23-0-0, 10 KO\u2019s. \u201cFue la mejor pelea de mi vida. Que ahora venga quien sea. Estoy listo para enfrentar a cualquiera\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNo se trat\u00f3 sobre lo que Puello hizo esta noche, sino que fue lo que yo no logr\u00e9 hacer. Deb\u00ed haber escuchado y ejecutado m\u00e1s y mejor. Es lo que siempre digo, es un hecho que voy a ganar si ejecuto nuestra estrategia. Hoy me qued\u00e9 corto en ese aspecto\u201d, reconoci\u00f3 Russell que perdi\u00f3 su invicto como profesional (17-1-0, 17 KO\u2019s). \u201cYo siempre ser\u00e9 un buen deportista. Felicitaciones a Puello, y a volver a empezar\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NEVADA.- El peleador dominicano Carlos Adames derrot\u00f3 de manera un\u00e1nime al estadounidense Terrell Gausha para retener el t\u00edtulo de peso mediano del Consejo Mundial de Boxeo (CMB) en el MGM Grand Garden Arena de Las Vegas. En su&nbsp;primera defensa, despu\u00e9s de ser ascendido de campe\u00f3n interino a monarca absoluto, Adames solvent\u00f3 la oposici\u00f3n del ol\u00edmpico estadounidense, aunque no pudo noquearlo.&nbsp;Dos jueces votaron id\u00e9ntico 119-109 y el tercero 118-110, todos a favor del quisqueyano. \u201cEsta fue una victoria muy satisfactoria, habiendo defendido mi titulo de la manera que lo hice con una decisi\u00f3n contundente. Era lo que quer\u00eda tras haber pasado un a\u00f1o sin pelear, dijo Adames. Fue un combate de pocos golpes y seg\u00fan el conteo de&nbsp;Compubox, ambos peleadores aterrizaron 107 golpes y lanzaron la misma cantidad de golpes de poder: 200. La pelea fue m\u00e1s pareja de lo que reflejaron las tarjetas de los imparciales. Adames tom\u00f3 la iniciativa e impuso el ritmo con combinaciones de golpes a la cabeza y las zonas blandas. \u201cEl nocaut estaba latente hasta que conect\u00e9 ese golpe bajo sin querer. Fue desafortunado. (Gausha) se pudo recomponer y tomar aire despu\u00e9s de eso. Supo ser un rival inc\u00f3modo para m\u00ed\u201d, agreg\u00f3 el dominicano en la conferencia de prensa. \u201c\u00a1Lo mejor est\u00e1 por venir! Quiero darle las gracias a la gente por haber venido a apoyarme\u201d. Gausha por momentos se meti\u00f3 en el combate, pero el exceso de cautela le pas\u00f3 factura ante el ojo de los jueces. \u201cCarlos Adames es un gran boxeador con una pegada potente, as\u00ed que yo sab\u00eda que deb\u00eda ser cauteloso en los rounds iniciales. Mi estrategia era ser m\u00e1s agresivo en los asaltos finales, y yo pens\u00e9 que lo hab\u00eda sido, pero eso obviamente no alcanz\u00f3 esta noche\u201d, coment\u00f3 Gausha. \u201cEl margen de las tarjetas fue amplio y no estuve de acuerdo con ellas. Pens\u00e9 que hab\u00eda sido una pelea m\u00e1s re\u00f1ida, pero al final \u00e9l gan\u00f3 la pelea y no se puede hacer nada al respecto. Con la victoria, el peleador dominicano de 30 a\u00f1os mejor\u00f3 su r\u00e9cord a 24-1-0, 18 KO\u2019s. En tanto, Gausha, de 36, dej\u00f3 su balance profesional en 24-4-1, 12 KO\u2019s. \u201cEstoy bendecido por hacer lo que amo a los 36 a\u00f1os de edad sin lesiones y una gran capacidad defensiva. Simplemente debo volver al pizarr\u00f3n y ya veremos que haremos\u201d, concluy\u00f3 el pugilista estadounidense que fall\u00f3 por tercera ocasi\u00f3n en una oportunidad titular. Puello sorprende y derrota a Gary Antuanne Russell Alberto Puello&nbsp;complet\u00f3 la fiesta para la Rep\u00fablica Dominicana al superar contra todo pron\u00f3stico al hasta entonces invicto estadounidense&nbsp;Gary Antuanne Russell&nbsp;y as\u00ed agenciarse el&nbsp;t\u00edtulo interino superligero del CMB. La victoria de Puello lleg\u00f3 por decisi\u00f3n dividida.&nbsp;Un juez vot\u00f3 118-109 para Rusell, pero los otros le dieron el veredicto al dominicano 115-112 y 114-113. \u201cCuando celebr\u00e9 cayendo de rodillas al suelo, lo primero que hice fue darle las gracias a Dios, y luego dije \u2018lo logr\u00e9\u2019. La barrera del peso y el tiempo pasado lejos de mi familia valieron la pena despu\u00e9s de todo\u201d, dijo despu\u00e9s del combate el peleador de 29 a\u00f1os de San Juan de la Maguana. La precisi\u00f3n en el contragolpe de \u2018La Avispa\u2019 Puello hizo la diferencia, a pesar de que le quitaron un punto en el round 9 por aguantar. De acuerdo con Compubox, tuvo una efectividad del 26.6% (aterriz\u00f3 112 de 425 golpes lanzados, superior al 16.2% (100 de 619) de Russell. \u201cEl ser campe\u00f3n se siente fenomenal, ya que este momento marca un antes y un despu\u00e9s en mi carrera y en mi vida\u201d, indic\u00f3 Puello que mejor\u00f3 su r\u00e9cord a 23-0-0, 10 KO\u2019s. \u201cFue la mejor pelea de mi vida. Que ahora venga quien sea. Estoy listo para enfrentar a cualquiera\u201d. \u201cNo se trat\u00f3 sobre lo que Puello hizo esta noche, sino que fue lo que yo no logr\u00e9 hacer. Deb\u00ed haber escuchado y ejecutado m\u00e1s y mejor. Es lo que siempre digo, es un hecho que voy a ganar si ejecuto nuestra estrategia. Hoy me qued\u00e9 corto en ese aspecto\u201d, reconoci\u00f3 Russell que perdi\u00f3 su invicto como profesional (17-1-0, 17 KO\u2019s). \u201cYo siempre ser\u00e9 un buen deportista. Felicitaciones a Puello, y a volver a empezar\u201d.<\/p>\n","protected":false},"author":9,"featured_media":96866,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-96865","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=96865"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96865\/revisions"}],"predecessor-version":[{"id":96867,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96865\/revisions\/96867"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/96866"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=96865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=96865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=96865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}