{"id":96874,"date":"2024-06-18T07:08:39","date_gmt":"2024-06-18T11:08:39","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=96874"},"modified":"2024-06-18T07:08:40","modified_gmt":"2024-06-18T11:08:40","slug":"atribuye-apagones-al-calor-hay-generacion-suficiente-en-la-rd","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/atribuye-apagones-al-calor-hay-generacion-suficiente-en-la-rd\/","title":{"rendered":"Atribuye apagones al calor, \u00abhay generaci\u00f3n suficiente\u00bb en la RD"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-17-at-7.00.39-PM-1024x570.jpeg\" alt=\"\" class=\"wp-image-96876\" width=\"229\" height=\"127\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-17-at-7.00.39-PM-1024x570.jpeg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-17-at-7.00.39-PM-300x167.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-17-at-7.00.39-PM-768x428.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-17-at-7.00.39-PM-600x334.jpeg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-17-at-7.00.39-PM.jpeg 1280w\" sizes=\"auto, (max-width: 229px) 100vw, 229px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">SANTO DOMINGO.- El presidente de la Rep\u00fablica, Luis Abinader, atribuy\u00f3 la tanda de apagones que se han registrado en las \u00faltimas semanas a la ola de calor que ha afectado al pa\u00eds en igual per\u00edodo y dijo no son por falta de generaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su encuentro La Semanal con la Prensa sostuvo que el Gobierno se ha mantenido comprando millones de d\u00f3lares en transformadores, de los cuales muchos han llegado y sirven como amortiguadores de circuitos que se sobrecalientan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Mandatario asegur\u00f3 que, aunque una de las plantas de Punta Catalina se encuentra en mantenimiento, en el pa\u00eds no hay apagones por falta de generaci\u00f3n, aunque s\u00ed ya est\u00e1 al tope.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>GOBIERNO LICITO MAS DE 2 MIL MEGAS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Abinader adelant\u00f3 que el Gobierno ha licitado m\u00e1s de 2 mil megas, de los cuales ya hay operando unos 400, los cuales han servido para mitigar los efectos del calor en la energ\u00eda el\u00e9ctrica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asegur\u00f3 que de no tener esos megas en operaci\u00f3n, producto de una licitaci\u00f3n de emergencia, en el pa\u00eds habr\u00edan \u201cmuchos apagones\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abSi hubiera muchos apagones por renovaci\u00f3n, no los hay, adem\u00e1s de las renovables que hay. Los apagones que hay es por lo que pasa todos los a\u00f1os con el tema del calor, no ha habido una inversi\u00f3n en las redes\u00bb, manifest\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Jefe de Estado dijo que \u00abhemos comprado millones de d\u00f3lares en transformadores, una parte ha ido llegando y otras vienen en camino para fortalecer los circuitos que se sobrecalientan\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- El presidente de la Rep\u00fablica, Luis Abinader, atribuy\u00f3 la tanda de apagones que se han registrado en las \u00faltimas semanas a la ola de calor que ha afectado al pa\u00eds en igual per\u00edodo y dijo no son por falta de generaci\u00f3n. En su encuentro La Semanal con la Prensa sostuvo que el Gobierno se ha mantenido comprando millones de d\u00f3lares en transformadores, de los cuales muchos han llegado y sirven como amortiguadores de circuitos que se sobrecalientan. El Mandatario asegur\u00f3 que, aunque una de las plantas de Punta Catalina se encuentra en mantenimiento, en el pa\u00eds no hay apagones por falta de generaci\u00f3n, aunque s\u00ed ya est\u00e1 al tope. GOBIERNO LICITO MAS DE 2 MIL MEGAS Abinader adelant\u00f3 que el Gobierno ha licitado m\u00e1s de 2 mil megas, de los cuales ya hay operando unos 400, los cuales han servido para mitigar los efectos del calor en la energ\u00eda el\u00e9ctrica. Asegur\u00f3 que de no tener esos megas en operaci\u00f3n, producto de una licitaci\u00f3n de emergencia, en el pa\u00eds habr\u00edan \u201cmuchos apagones\u201d. \u00abSi hubiera muchos apagones por renovaci\u00f3n, no los hay, adem\u00e1s de las renovables que hay. Los apagones que hay es por lo que pasa todos los a\u00f1os con el tema del calor, no ha habido una inversi\u00f3n en las redes\u00bb, manifest\u00f3. El Jefe de Estado dijo que \u00abhemos comprado millones de d\u00f3lares en transformadores, una parte ha ido llegando y otras vienen en camino para fortalecer los circuitos que se sobrecalientan\u00bb<\/p>\n","protected":false},"author":9,"featured_media":96876,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-96874","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=96874"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96874\/revisions"}],"predecessor-version":[{"id":96877,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96874\/revisions\/96877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/96876"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=96874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=96874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=96874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}