{"id":96932,"date":"2024-06-21T06:41:19","date_gmt":"2024-06-21T10:41:19","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=96932"},"modified":"2024-06-21T06:41:20","modified_gmt":"2024-06-21T10:41:20","slug":"vias-y-aceras-obstruidas-cierran-paso-a-la-gente","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/vias-y-aceras-obstruidas-cierran-paso-a-la-gente\/","title":{"rendered":"V\u00edas y aceras obstruidas cierran paso a la gente"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/6674cde1ed1ba.jpeg\" alt=\"\" class=\"wp-image-96933\" width=\"211\" height=\"102\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/6674cde1ed1ba.jpeg 950w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/6674cde1ed1ba-300x147.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/6674cde1ed1ba-768x376.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/6674cde1ed1ba-600x294.jpeg 600w\" sizes=\"auto, (max-width: 211px) 100vw, 211px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Caminar por las calles de la capital no es tarea dif\u00edcil, pero tampoco f\u00e1cil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ponerse en el lugar de una persona ciega, en silla de ruedas o con alguna dificultad para caminar y salir a las calles, chocar\u00eda con una realidad lacerante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo que deber\u00eda ser un espacio seguro para los peatones, se ha convertido en un caos urbano lleno de negocios que han provocado da\u00f1os en algunas zonas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si llegas a Villa Juana, lo primero que te saluda es un puesto de venta de comida con sus desechos de su lado, no en un dep\u00f3sito para basura. Muchos est\u00e1n en cada esquina, abarcando desde la acera hasta la calle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los talleres de reparaci\u00f3n de veh\u00edculos con sus neum\u00e1ticos por doquier, herramientas y los mismos clientes que se sientan en las aceras. A esto se agregan letreros que hacen atraer a la gente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seguido de estas principales obstrucciones en las aceras, est\u00e1n los veh\u00edculos. En las calles que se ven los puestos de comida y talleres no se pueden quedar los veh\u00edculos estacionados, muchos abarcan varias cuadras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Resulta dif\u00edcil no toparse con un puesto de empanadas, frituras, venta de caf\u00e9 o alguna acera da\u00f1ada obstruyendo este sector.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En algunos puntos, c\u00f3mo es en la calle Am\u00e9rico Lugo, ni aceras hay. En otras, la mayor\u00eda se ven amplias y f\u00e1ciles de circular, pero una que otra destruida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otra zona muy habitada, pero dif\u00edcil de transitar es Villas Agr\u00edcolas. Aqu\u00ed la cosa se va poniendo peor, pues el nivel de aceras con da\u00f1os es m\u00e1s alto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La basura abarca muchas aceras de varias calles a pesar de que algunos residentes comentaron que el cami\u00f3n de la basura pasa con frecuencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aqu\u00ed tambi\u00e9n los residentes se adue\u00f1an de las veredas. Los motoristas hasta instalan filas de asientos para postrarse mientras esperan a sus pasajeros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Muchas son las personas que transitan en las calles, pues no les queda de otra. En la calle Juan Erazo los puestos de vendedores informales abarcan la mayor\u00eda de las aceras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ya en este paso resulta complicado atravesar alguno de estos sectores sin tener alguna dificultad, ahora, tener consigo una dificultad ser\u00eda una traves\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta construcciones en plena vereda donde los constructores dejan sus utensilios en las calles. Junto a esto tambi\u00e9n hay talleres de soldadura en la acera sin ning\u00fan tipo de cuidado para las personas que caminan alrededor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una de las calles de esta zona, la Moca, es un claro ejemplo de la invasi\u00f3n de espacios p\u00fablicos, donde los negocios informales hacen imposible el tr\u00e1nsito peatonal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas dificultades para la gente tambi\u00e9n las tienen los colmados, pues no se quedan atr\u00e1s, hasta la mercanc\u00eda que les va llegando la colocan tambi\u00e9n junto a sus motores de delivery estacionados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A la hora de abordar alg\u00fan veh\u00edculo, los transe\u00fantes deben esperar en las calles, pues no les queda de otra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Llegando ya a Villa Consuelo, las casas que se encuentran en las principales avenidas no dejan las aceras libres, pues est\u00e1n construidas hasta la calle, dejando el cont\u00e9n como espacio divisorio entre las casas y la calle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Villa Consuelo es donde se visualizan las peores condiciones para transitar, desde zonas que ni aceras tienen hasta negocios que las han destruido para apropiarse de esos espacios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de que en los parques exista una que otra rampa para acceder desde la calle, los comerciantes que han invadido las aceras no permiten que se pueda llegar a estos o las aceras est\u00e1n en malas condiciones<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tienen que recurrir a las calles porque las veredas que est\u00e1n hechas para la gente la ocupan los carros, est\u00e1n da\u00f1adas o invadidas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Caminar por las calles de la capital no es tarea dif\u00edcil, pero tampoco f\u00e1cil. Ponerse en el lugar de una persona ciega, en silla de ruedas o con alguna dificultad para caminar y salir a las calles, chocar\u00eda con una realidad lacerante. Lo que deber\u00eda ser un espacio seguro para los peatones, se ha convertido en un caos urbano lleno de negocios que han provocado da\u00f1os en algunas zonas. Si llegas a Villa Juana, lo primero que te saluda es un puesto de venta de comida con sus desechos de su lado, no en un dep\u00f3sito para basura. Muchos est\u00e1n en cada esquina, abarcando desde la acera hasta la calle. Los talleres de reparaci\u00f3n de veh\u00edculos con sus neum\u00e1ticos por doquier, herramientas y los mismos clientes que se sientan en las aceras. A esto se agregan letreros que hacen atraer a la gente. Seguido de estas principales obstrucciones en las aceras, est\u00e1n los veh\u00edculos. En las calles que se ven los puestos de comida y talleres no se pueden quedar los veh\u00edculos estacionados, muchos abarcan varias cuadras. Resulta dif\u00edcil no toparse con un puesto de empanadas, frituras, venta de caf\u00e9 o alguna acera da\u00f1ada obstruyendo este sector. En algunos puntos, c\u00f3mo es en la calle Am\u00e9rico Lugo, ni aceras hay. En otras, la mayor\u00eda se ven amplias y f\u00e1ciles de circular, pero una que otra destruida. Otra zona muy habitada, pero dif\u00edcil de transitar es Villas Agr\u00edcolas. Aqu\u00ed la cosa se va poniendo peor, pues el nivel de aceras con da\u00f1os es m\u00e1s alto. La basura abarca muchas aceras de varias calles a pesar de que algunos residentes comentaron que el cami\u00f3n de la basura pasa con frecuencia. Aqu\u00ed tambi\u00e9n los residentes se adue\u00f1an de las veredas. Los motoristas hasta instalan filas de asientos para postrarse mientras esperan a sus pasajeros. Muchas son las personas que transitan en las calles, pues no les queda de otra. En la calle Juan Erazo los puestos de vendedores informales abarcan la mayor\u00eda de las aceras. Ya en este paso resulta complicado atravesar alguno de estos sectores sin tener alguna dificultad, ahora, tener consigo una dificultad ser\u00eda una traves\u00eda. Hasta construcciones en plena vereda donde los constructores dejan sus utensilios en las calles. Junto a esto tambi\u00e9n hay talleres de soldadura en la acera sin ning\u00fan tipo de cuidado para las personas que caminan alrededor. Una de las calles de esta zona, la Moca, es un claro ejemplo de la invasi\u00f3n de espacios p\u00fablicos, donde los negocios informales hacen imposible el tr\u00e1nsito peatonal. Estas dificultades para la gente tambi\u00e9n las tienen los colmados, pues no se quedan atr\u00e1s, hasta la mercanc\u00eda que les va llegando la colocan tambi\u00e9n junto a sus motores de delivery estacionados. A la hora de abordar alg\u00fan veh\u00edculo, los transe\u00fantes deben esperar en las calles, pues no les queda de otra. Llegando ya a Villa Consuelo, las casas que se encuentran en las principales avenidas no dejan las aceras libres, pues est\u00e1n construidas hasta la calle, dejando el cont\u00e9n como espacio divisorio entre las casas y la calle. En Villa Consuelo es donde se visualizan las peores condiciones para transitar, desde zonas que ni aceras tienen hasta negocios que las han destruido para apropiarse de esos espacios. A pesar de que en los parques exista una que otra rampa para acceder desde la calle, los comerciantes que han invadido las aceras no permiten que se pueda llegar a estos o las aceras est\u00e1n en malas condiciones Tienen que recurrir a las calles porque las veredas que est\u00e1n hechas para la gente la ocupan los carros, est\u00e1n da\u00f1adas o invadidas.<\/p>\n","protected":false},"author":9,"featured_media":96933,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-96932","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=96932"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96932\/revisions"}],"predecessor-version":[{"id":96934,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/96932\/revisions\/96934"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/96933"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=96932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=96932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=96932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}