{"id":97005,"date":"2024-06-26T07:30:27","date_gmt":"2024-06-26T11:30:27","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=97005"},"modified":"2024-06-26T07:30:29","modified_gmt":"2024-06-26T11:30:29","slug":"importadores-bebidas-apoyan-la-lucha-contra-el-comercio-ilicito","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/importadores-bebidas-apoyan-la-lucha-contra-el-comercio-ilicito\/","title":{"rendered":"Importadores bebidas apoyan la lucha contra el comercio il\u00edcito"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/Importadores-de-bebidas-alcoholicas-apoyan-esfuerzos.jpg\" alt=\"\" class=\"wp-image-97006\" width=\"208\" height=\"127\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/Importadores-de-bebidas-alcoholicas-apoyan-esfuerzos.jpg 940w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/Importadores-de-bebidas-alcoholicas-apoyan-esfuerzos-300x184.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/Importadores-de-bebidas-alcoholicas-apoyan-esfuerzos-768x471.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/Importadores-de-bebidas-alcoholicas-apoyan-esfuerzos-600x368.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/Importadores-de-bebidas-alcoholicas-apoyan-esfuerzos-440x270.jpg 440w\" sizes=\"auto, (max-width: 208px) 100vw, 208px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SANTO DOMINGO.-<\/strong>&nbsp;El sector importador de bebidas alcoh\u00f3licas expres\u00f3 su apoyo a la colaboraci\u00f3n p\u00fablico-privada para la lucha contra el comercio il\u00edcito, tras la incineraci\u00f3n y destrucci\u00f3n de m\u00e1s de 20 millones unidades de mercanc\u00edas il\u00edcitas, decomisadas a trav\u00e9s de operativos llevados a cabo en todo el territorio nacional, durante el a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl incremento del comercio il\u00edcito es uno de los retos m\u00e1s grandes que enfrenta el sector de bebidas alcoh\u00f3licas, perjudicando&nbsp;la salud de los consumidores, reduciendo el n\u00famero de empleos formales disponibles, disminuyendo los ingresos del Estado, y creando distorsiones en el mercado formal.&nbsp; En el a\u00f1o 2021, se estim\u00f3 que el comercio il\u00edcito le cost\u00f3 al Estado Dominicano cerca de RD$3,000 millones en ingresos no captados, sin tomar en cuenta lo m\u00e1s importante que son p\u00e9rdidas humanas causadas por el il\u00edcito, o los recursos utilizados para combatirlo\u201d, resaltaron los importadores de bebidas alcoh\u00f3licas, haciendo hincapi\u00e9 igualmente en la importancia de la lucha contra estos il\u00edcitos para la sostenibilidad econ\u00f3mica del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 2023, los importadores de bebidas alcoh\u00f3licas aportaron alrededor de RD$15,100 millones al fisco, lo que represent\u00f3 el 7% de los ingresos fiscales de aduanas durante este a\u00f1o. De la misma forma, las bebidas importadas representaron un 2% de los impuestos captados por el Estado durante este a\u00f1o, y son una fuerza dinamizadora de la econom\u00eda, contando con m\u00e1s de 3,000 proveedores locales, y generando m\u00e1s de 6,000 empleos directos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs importante resaltar que, seg\u00fan la experiencia de la reforma tributaria del 2012, los aumentos&nbsp;importantes de impuestos a las bebidas alcoh\u00f3licas incrementan significativamente el comercio il\u00edcito. Este fue el caso en los a\u00f1os 2013 y 2014, donde&nbsp;economistas resaltaron&nbsp;las&nbsp;recaudaciones reales disminuyeron, gracias al comercio il\u00edcito.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las mercanc\u00edas incineradas y destruidas en la \u00faltima iniciativa fueron decomisadas por el MICM a trav\u00e9s de diversos operativos realizados por el Cuerpo Especializado de Control de Combustible y de Mercanc\u00edas (Ceccom), y ProConsumidor. Estas incluyeron 8,943,783 unidades de cigarrillos, 853,959 unidades de medicamentos, 21,841 botellas de alcohol il\u00edcito, 6,301 unidades de estimulantes sexuales, y 1,157 alcoholes tipo cler\u00e9n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos resultados son fruto de una colaboraci\u00f3n p\u00fablico-privada en el desarrollo de pol\u00edticas p\u00fablicas efectivas y eficaces, las cuales protegen la vida y salud de todos los dominicanos. En representaci\u00f3n del sector privado, la asociaci\u00f3n Representantes Importadores de Vinos y Licores Asociados (RIVLAS) agradeci\u00f3 al ministro Bison\u00f3, al igual que al CECCOM por su labor clave en la lucha contra el comercio il\u00edcito. De la misma forma, saludaron los esfuerzos incansables de la Procuradur\u00eda General de la Rep\u00fablica, el Instituto Nacional de Protecci\u00f3n de los Derechos del Consumidor (ProConsumidor), Direcci\u00f3n General de Medicamentos, Alimentos y Productos Sanitarios (DIGEMAPS), el Ej\u00e9rcito de la Rep\u00fablica Dominicana, el Cuerpo Especializado en Seguridad Fronteriza Terrestre (Cesfront) , Ministerio de Salud, y la Procuradur\u00eda Especializada de Cr\u00edmenes y Delitos contra la Salud (Pedecsa), al igual que dem\u00e1s instituciones p\u00fablicas y privadas involucradas en estos esfuerzos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre RIVLAS:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Asociaci\u00f3n Representantes e Importadores de Vinos y Licores Asociados (RIVLAS) representa a m\u00e1s del 85% de los importadores de bebidas alcoh\u00f3licas en la Rep\u00fablica Dominicana. Lleva 37 a\u00f1os trabajando con sus socios en aras de promover e incorporar los m\u00e1s altos est\u00e1ndares de calidad y las mejores pr\u00e1cticas en el sector de bebidas alcoh\u00f3licas del pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.-&nbsp;El sector importador de bebidas alcoh\u00f3licas expres\u00f3 su apoyo a la colaboraci\u00f3n p\u00fablico-privada para la lucha contra el comercio il\u00edcito, tras la incineraci\u00f3n y destrucci\u00f3n de m\u00e1s de 20 millones unidades de mercanc\u00edas il\u00edcitas, decomisadas a trav\u00e9s de operativos llevados a cabo en todo el territorio nacional, durante el a\u00f1o. \u201cEl incremento del comercio il\u00edcito es uno de los retos m\u00e1s grandes que enfrenta el sector de bebidas alcoh\u00f3licas, perjudicando&nbsp;la salud de los consumidores, reduciendo el n\u00famero de empleos formales disponibles, disminuyendo los ingresos del Estado, y creando distorsiones en el mercado formal.&nbsp; En el a\u00f1o 2021, se estim\u00f3 que el comercio il\u00edcito le cost\u00f3 al Estado Dominicano cerca de RD$3,000 millones en ingresos no captados, sin tomar en cuenta lo m\u00e1s importante que son p\u00e9rdidas humanas causadas por el il\u00edcito, o los recursos utilizados para combatirlo\u201d, resaltaron los importadores de bebidas alcoh\u00f3licas, haciendo hincapi\u00e9 igualmente en la importancia de la lucha contra estos il\u00edcitos para la sostenibilidad econ\u00f3mica del pa\u00eds. En 2023, los importadores de bebidas alcoh\u00f3licas aportaron alrededor de RD$15,100 millones al fisco, lo que represent\u00f3 el 7% de los ingresos fiscales de aduanas durante este a\u00f1o. De la misma forma, las bebidas importadas representaron un 2% de los impuestos captados por el Estado durante este a\u00f1o, y son una fuerza dinamizadora de la econom\u00eda, contando con m\u00e1s de 3,000 proveedores locales, y generando m\u00e1s de 6,000 empleos directos. \u201cEs importante resaltar que, seg\u00fan la experiencia de la reforma tributaria del 2012, los aumentos&nbsp;importantes de impuestos a las bebidas alcoh\u00f3licas incrementan significativamente el comercio il\u00edcito. Este fue el caso en los a\u00f1os 2013 y 2014, donde&nbsp;economistas resaltaron&nbsp;las&nbsp;recaudaciones reales disminuyeron, gracias al comercio il\u00edcito.\u201d Las mercanc\u00edas incineradas y destruidas en la \u00faltima iniciativa fueron decomisadas por el MICM a trav\u00e9s de diversos operativos realizados por el Cuerpo Especializado de Control de Combustible y de Mercanc\u00edas (Ceccom), y ProConsumidor. Estas incluyeron 8,943,783 unidades de cigarrillos, 853,959 unidades de medicamentos, 21,841 botellas de alcohol il\u00edcito, 6,301 unidades de estimulantes sexuales, y 1,157 alcoholes tipo cler\u00e9n. Estos resultados son fruto de una colaboraci\u00f3n p\u00fablico-privada en el desarrollo de pol\u00edticas p\u00fablicas efectivas y eficaces, las cuales protegen la vida y salud de todos los dominicanos. En representaci\u00f3n del sector privado, la asociaci\u00f3n Representantes Importadores de Vinos y Licores Asociados (RIVLAS) agradeci\u00f3 al ministro Bison\u00f3, al igual que al CECCOM por su labor clave en la lucha contra el comercio il\u00edcito. De la misma forma, saludaron los esfuerzos incansables de la Procuradur\u00eda General de la Rep\u00fablica, el Instituto Nacional de Protecci\u00f3n de los Derechos del Consumidor (ProConsumidor), Direcci\u00f3n General de Medicamentos, Alimentos y Productos Sanitarios (DIGEMAPS), el Ej\u00e9rcito de la Rep\u00fablica Dominicana, el Cuerpo Especializado en Seguridad Fronteriza Terrestre (Cesfront) , Ministerio de Salud, y la Procuradur\u00eda Especializada de Cr\u00edmenes y Delitos contra la Salud (Pedecsa), al igual que dem\u00e1s instituciones p\u00fablicas y privadas involucradas en estos esfuerzos. Sobre RIVLAS: La Asociaci\u00f3n Representantes e Importadores de Vinos y Licores Asociados (RIVLAS) representa a m\u00e1s del 85% de los importadores de bebidas alcoh\u00f3licas en la Rep\u00fablica Dominicana. Lleva 37 a\u00f1os trabajando con sus socios en aras de promover e incorporar los m\u00e1s altos est\u00e1ndares de calidad y las mejores pr\u00e1cticas en el sector de bebidas alcoh\u00f3licas del pa\u00eds.<\/p>\n","protected":false},"author":9,"featured_media":97006,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-97005","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/97005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=97005"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/97005\/revisions"}],"predecessor-version":[{"id":97007,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/97005\/revisions\/97007"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/97006"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=97005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=97005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=97005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}