{"id":97036,"date":"2024-06-28T07:10:57","date_gmt":"2024-06-28T11:10:57","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=97036"},"modified":"2024-06-28T07:10:59","modified_gmt":"2024-06-28T11:10:59","slug":"el-gran-negocio-con-las-parturientas-haitianas-opinion","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/el-gran-negocio-con-las-parturientas-haitianas-opinion\/","title":{"rendered":"El gran negocio con las parturientas haitianas (OPINION)"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"166\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/gran-300x166-1.jpg\" alt=\"\" class=\"wp-image-97037\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras una parte de la comunidad internacional encabezada por la Uni\u00f3n Europea y Estados Unidos acusan a la Rep\u00fablica Dominicana de maltratos a los ciudadanos de origen haitiano que residen en el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras Estados Unidos presiona para que Rep\u00fablica Dominicana&nbsp; otorgue alg\u00fan tipo de ciudadan\u00eda a los haitianos permanentes en suelo dominicano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras la Rep\u00fablica de Hait\u00ed se encuentra sumida en el m\u00e1s absoluto caos luego del asesinato de su Presidente Jovenel Moises.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras el gobierno dominicano hace presencia militar permanente en la frontera con Hait\u00ed en busca de frenar la inmigraci\u00f3n de haitianos y ciudadanos de otras nacionales que cruzan de manera ilegal esa zona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras todo eso pasa, existe un negocio colosal de traer mujeres haitianas pre\u00f1adas a dar a luz en la Rep\u00fablica Dominicana sin que supuestamente ninguna autoridad nacional se d\u00e9 cuenta a pesar de los pesares.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/almomento.net\/wp-content\/uploads\/2024\/04\/marino-ramirez-scaled-1-e1713353128791-300x249.jpg\" alt=\"\" class=\"wp-image-948351\" \/><figcaption>El autor es periodista<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El costo econ\u00f3mico y social que origina esta situaci\u00f3n an\u00f3mala &nbsp;es de miles de millones de pesos, mientras a los dominicanos se les hace dif\u00edcil acceder a la salud p\u00fablica debido a los malos servicios y falta de espacios que se origina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mafia que mueve el negocio de las parturientas haitianas no es tan antigua pero al mover aparentemente tanto dinero se pasa por alto y s\u00f3lo se persiguen a algunos traficantes de personas que mueven gente sana pero con ganas de salir de ese desorden institucionalizado que se llama Hait\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es todo un negocio que no ven los militares, migraci\u00f3n, funcionarios civiles, pol\u00edticos ni la verja perimetral construida para impedir el cruce ilegal de personas por la frontera com\u00fan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00f3lo ir a algunos hospitales de maternidad y ver las camas llenas de mujeres parturientas haitianas que s\u00f3lo vienen para eso, aunque al nacer sus hijos aqu\u00ed probablemente crezcan en la Rep\u00fablica Dominicana y con el tiempo se vuelvan ciudadanos nacionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En fin, es un tema de nunca acabar que nuestra democracia no ha podido solucionar ni creo que solucione, llegar\u00e1 el momento en que recordaremos lo que pas\u00f3 en Kosovo con los albaneses que nacieron all\u00ed y que&nbsp; ahora reclaman una Rep\u00fablica independiente con el apoyo de las potencias de la democracia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mientras una parte de la comunidad internacional encabezada por la Uni\u00f3n Europea y Estados Unidos acusan a la Rep\u00fablica Dominicana de maltratos a los ciudadanos de origen haitiano que residen en el pa\u00eds. Mientras Estados Unidos presiona para que Rep\u00fablica Dominicana&nbsp; otorgue alg\u00fan tipo de ciudadan\u00eda a los haitianos permanentes en suelo dominicano. Mientras la Rep\u00fablica de Hait\u00ed se encuentra sumida en el m\u00e1s absoluto caos luego del asesinato de su Presidente Jovenel Moises. Mientras el gobierno dominicano hace presencia militar permanente en la frontera con Hait\u00ed en busca de frenar la inmigraci\u00f3n de haitianos y ciudadanos de otras nacionales que cruzan de manera ilegal esa zona. Mientras todo eso pasa, existe un negocio colosal de traer mujeres haitianas pre\u00f1adas a dar a luz en la Rep\u00fablica Dominicana sin que supuestamente ninguna autoridad nacional se d\u00e9 cuenta a pesar de los pesares. El costo econ\u00f3mico y social que origina esta situaci\u00f3n an\u00f3mala &nbsp;es de miles de millones de pesos, mientras a los dominicanos se les hace dif\u00edcil acceder a la salud p\u00fablica debido a los malos servicios y falta de espacios que se origina. La mafia que mueve el negocio de las parturientas haitianas no es tan antigua pero al mover aparentemente tanto dinero se pasa por alto y s\u00f3lo se persiguen a algunos traficantes de personas que mueven gente sana pero con ganas de salir de ese desorden institucionalizado que se llama Hait\u00ed. Es todo un negocio que no ven los militares, migraci\u00f3n, funcionarios civiles, pol\u00edticos ni la verja perimetral construida para impedir el cruce ilegal de personas por la frontera com\u00fan. S\u00f3lo ir a algunos hospitales de maternidad y ver las camas llenas de mujeres parturientas haitianas que s\u00f3lo vienen para eso, aunque al nacer sus hijos aqu\u00ed probablemente crezcan en la Rep\u00fablica Dominicana y con el tiempo se vuelvan ciudadanos nacionales. En fin, es un tema de nunca acabar que nuestra democracia no ha podido solucionar ni creo que solucione, llegar\u00e1 el momento en que recordaremos lo que pas\u00f3 en Kosovo con los albaneses que nacieron all\u00ed y que&nbsp; ahora reclaman una Rep\u00fablica independiente con el apoyo de las potencias de la democracia.<\/p>\n","protected":false},"author":9,"featured_media":97037,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-97036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/97036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=97036"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/97036\/revisions"}],"predecessor-version":[{"id":97038,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/97036\/revisions\/97038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/97037"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=97036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=97036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=97036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}