{"id":97042,"date":"2024-06-28T07:15:30","date_gmt":"2024-06-28T11:15:30","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=97042"},"modified":"2024-06-28T07:15:32","modified_gmt":"2024-06-28T11:15:32","slug":"haiti-banda-desafia-quema-cabildo-y-demuele-una-prision","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/haiti-banda-desafia-quema-cabildo-y-demuele-una-prision\/","title":{"rendered":"Hait\u00ed: Banda desaf\u00eda; quema cabildo y demuele una prisi\u00f3n"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/HAITI-VIOLENCIA-e1719518685672-1024x640.jpg\" alt=\"\" class=\"wp-image-97043\" width=\"235\" height=\"147\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/HAITI-VIOLENCIA-e1719518685672-1024x640.jpg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/HAITI-VIOLENCIA-e1719518685672-300x188.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/HAITI-VIOLENCIA-e1719518685672-768x480.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/HAITI-VIOLENCIA-e1719518685672-600x375.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/HAITI-VIOLENCIA-e1719518685672.jpg 1089w\" sizes=\"auto, (max-width: 235px) 100vw, 235px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">PUERTO PRINCIPE.-&nbsp;La banda 400 Mawozo prendi\u00f3 fuego al ayuntamiento de Kwad\u00e8bouk\u00e8, en el departamento Occidental y quem\u00f3 un coche que estaba aparcado delante del ayuntamiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos bandidos continuaron demoliendo la prisi\u00f3n y la comisar\u00eda de polic\u00eda de Croix-des-Bouquets, que ya hab\u00edan saqueado el pasado mes de mayo, seg\u00fan el peri\u00f3dico haitiano Le Nouvelliste.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El primer ministro haitiano, Garry Conille, visit\u00f3 este mi\u00e9rcoles el emplazamiento del primer contingente de polic\u00edas kenianos llegados al pa\u00eds, la base de Clercine en la comuna de Tabarre, en el norte de Puerto Pr\u00edncipe, donde reiter\u00f3 su determinaci\u00f3n de recuperar el control del territorio en manos de las bandas armadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>PIDE PACIENCIA A LA POBLACI\u00d3N<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Estado haitiano cuenta desde este momento con el apoyo de las fuerzas de seguridad reci\u00e9n llegadas para recuperar el control del pa\u00eds \u201ccasa por casa, barrio por barrio, ciudad por ciudad\u201d, declar\u00f3 el jefe del Gobierno, que pidi\u00f3 paciencia a la poblaci\u00f3n y habl\u00f3 de los progresos obtenidos para erradicar la violencia de las pandillas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAvanzamos poco a poco. Sin embargo, invitamos a la poblaci\u00f3n a tener paciencia porque estamos en v\u00edsperas de un nuevo comienzo\u201d, dijo Conille, quien destac\u00f3 la importancia de esta misi\u00f3n en la lucha contra la inseguridad en el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SOLIDARIDAD Y GRATITUD CON MISION<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, en presencia de la jefa de la delegaci\u00f3n keniana, Monica Juma, expres\u00f3 la solidaridad y gratitud de su Gobierno y del pueblo haitiano a la Misi\u00f3n Multinacional de Apoyo a la Seguridad en Hait\u00ed (MMAS) para restablecer el orden en el pa\u00eds, que encabezar\u00e1 Kenia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El primer contingente de polic\u00edas kenianos lleg\u00f3 a Puerto Pr\u00edncipe en la ma\u00f1ana del martes, al aeropuerto internacional Toussaint Louverture, y en estas primeras horas en territorio haitiano los agentes han empezado a tomar contacto con la cr\u00edtica realidad que se vive en el pa\u00eds, donde hay miles de desplazados a causa de la violencia de las bandas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PUERTO PRINCIPE.-&nbsp;La banda 400 Mawozo prendi\u00f3 fuego al ayuntamiento de Kwad\u00e8bouk\u00e8, en el departamento Occidental y quem\u00f3 un coche que estaba aparcado delante del ayuntamiento. Estos bandidos continuaron demoliendo la prisi\u00f3n y la comisar\u00eda de polic\u00eda de Croix-des-Bouquets, que ya hab\u00edan saqueado el pasado mes de mayo, seg\u00fan el peri\u00f3dico haitiano Le Nouvelliste. El primer ministro haitiano, Garry Conille, visit\u00f3 este mi\u00e9rcoles el emplazamiento del primer contingente de polic\u00edas kenianos llegados al pa\u00eds, la base de Clercine en la comuna de Tabarre, en el norte de Puerto Pr\u00edncipe, donde reiter\u00f3 su determinaci\u00f3n de recuperar el control del territorio en manos de las bandas armadas. PIDE PACIENCIA A LA POBLACI\u00d3N El Estado haitiano cuenta desde este momento con el apoyo de las fuerzas de seguridad reci\u00e9n llegadas para recuperar el control del pa\u00eds \u201ccasa por casa, barrio por barrio, ciudad por ciudad\u201d, declar\u00f3 el jefe del Gobierno, que pidi\u00f3 paciencia a la poblaci\u00f3n y habl\u00f3 de los progresos obtenidos para erradicar la violencia de las pandillas. \u201cAvanzamos poco a poco. Sin embargo, invitamos a la poblaci\u00f3n a tener paciencia porque estamos en v\u00edsperas de un nuevo comienzo\u201d, dijo Conille, quien destac\u00f3 la importancia de esta misi\u00f3n en la lucha contra la inseguridad en el pa\u00eds. SOLIDARIDAD Y GRATITUD CON MISION Asimismo, en presencia de la jefa de la delegaci\u00f3n keniana, Monica Juma, expres\u00f3 la solidaridad y gratitud de su Gobierno y del pueblo haitiano a la Misi\u00f3n Multinacional de Apoyo a la Seguridad en Hait\u00ed (MMAS) para restablecer el orden en el pa\u00eds, que encabezar\u00e1 Kenia. El primer contingente de polic\u00edas kenianos lleg\u00f3 a Puerto Pr\u00edncipe en la ma\u00f1ana del martes, al aeropuerto internacional Toussaint Louverture, y en estas primeras horas en territorio haitiano los agentes han empezado a tomar contacto con la cr\u00edtica realidad que se vive en el pa\u00eds, donde hay miles de desplazados a causa de la violencia de las bandas.<\/p>\n","protected":false},"author":9,"featured_media":97043,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-97042","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/97042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=97042"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/97042\/revisions"}],"predecessor-version":[{"id":97044,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/97042\/revisions\/97044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/97043"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=97042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=97042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=97042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}