{"id":9706,"date":"2014-10-22T01:14:47","date_gmt":"2014-10-22T05:14:47","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=9706"},"modified":"2014-10-22T01:14:47","modified_gmt":"2014-10-22T05:14:47","slug":"que-hacer-cuando-una-ex-pareja-no-te-deja-en-paz","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/que-hacer-cuando-una-ex-pareja-no-te-deja-en-paz\/","title":{"rendered":"\u00bfQu\u00e9 hacer cuando una ex pareja no te deja en paz?"},"content":{"rendered":"<div class=\"field field-name-field-summary field-type-text-long field-label-hidden view-mode-full\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/tu-ex-te-hostiga.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9707 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/tu-ex-te-hostiga.jpg\" alt=\"tu ex te hostiga\" width=\"600\" height=\"450\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/tu-ex-te-hostiga.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/10\/tu-ex-te-hostiga-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><br \/>\nAunque es halagador que alguien se interese en ti, cuando esa persona sobrepasa los l\u00edmites e invade tu espacio <label>personal<\/label>, la situaci\u00f3n puede volverse aterradora. Especialmente, cuando se trata de una <label>ex<\/label> pareja o una persona con la que saliste.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p><!--more--><\/p>\n<div class=\"field field-name-field-image field-type-image field-label-hidden view-mode-full\"><\/div>\n<div class=\"field field-name-body field-type-text-with-summary field-label-hidden view-mode-full\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>En este contexto, algunos expertos conversaron con la revista masculina Men\u2019s Health y explicaron qu\u00e9 hacer en 4 situaciones espec\u00edficas.<\/p>\n<p><strong>1. Te acosa y vigila en <label>redes sociales<\/label><\/strong><\/p>\n<p>La abogada y escritora estadounidense Wendy L. Patrick, dice que \u201catr\u00e1s quedaron los d\u00edas en que un amante despechado simplemente pasaba por delante de la <label>casa<\/label> de su ex\u201d.<\/p>\n<p>\u201cAhora la gente se acecha entre s\u00ed en <label>internet<\/label>, a trav\u00e9s de amigos de amigos de Facebook, o a trav\u00e9s de dispositivos GPS h\u00e1bilmente colocados\u201d, explica.<\/p>\n<p>Si tu ex siempre tiene algo que decir acerca de todas tus actualizaciones de estado, est\u00e1 constantemente pidi\u00e9ndote explicaciones por lo que haces en redes sociales, te acosa virtualmente o usa informaci\u00f3n en tu contra, puede ser un problema.<\/p>\n<p>Cuando esto ocurre, Patrick recomienda bloquear definitivamente a la persona en todas las redes sociales, y adem\u00e1s ajustar la configuraci\u00f3n de privacidad para que la gente indeseada no pueda husmear en tus cosas. Debes tener especial cuidado, porque algunos acosadores expertos pueden de todas maneras espiarte si lo desean. Por eso, a pesar de estas medidas se cauteloso con lo que publicas.<\/p>\n<p><strong>2. Te hace sentir culpable<\/strong><\/p>\n<p>Robert T. Muller, doctor en psicolog\u00eda y profesor en la Universidad de York especialista en trauma y apego, se\u00f1ala que algunas personas se obsesionan con quienes tuvieron una relaci\u00f3n muy corta, o con alguien con quien estuvieron una o dos veces porque se sienten menospreciadas.<\/p>\n<p>Seg\u00fan \u00e9l, es probable que de ser as\u00ed te sientas culpable por haberlo\/a abandonado y a\u00fan te preocupes por \u00e9l o ella, permitiendo que te siga acechando. \u201cRecuerda que muchos acosadores malinterpretan mensajes inocentes como algo rom\u00e1ntico. Dan significados sexuales a la comunicaci\u00f3n neutral y con frecuencia toman esto como est\u00edmulo\u201d, dice el psic\u00f3logo, por lo que recomienda cortar el contacto en forma definitiva, dejando de lado la culpa.<\/p>\n<p><strong>3. Qued\u00f3 mal psicol\u00f3gicamente tras la ruptura<\/strong><\/p>\n<p>\u201cDespu\u00e9s de una ruptura, por desgracia, algunas personas pueden sufrir un deterioro psicol\u00f3gico\u201d dice Muller, a\u00f1adiendo que incluso individuos sanos sin antecedentes de enfermedad mental pueden caer en h\u00e1bitos de acecho. Adem\u00e1s, la depresi\u00f3n y el estr\u00e9s psicol\u00f3gico pueden derivar a trastornos como la paranoia o trastorno bipolar subyacente. Si su personalidad parece haber tomado un giro dr\u00e1stico, puede ser se\u00f1al de algo m\u00e1s complejo que el t\u00edpico proceso post ruptura.<\/p>\n<p>En este sentido, lo mejor es recurrir a alg\u00fan miembro de su familia y manifestarle que est\u00e1s preocupado por su salud mental. Sin embargo, al mismo tiempo es importante que te alejes de la persona, ya que \u00e9sta podr\u00eda pensar que a\u00fan tienes sentimientos por ella, darle falsas expectativas y alimentar su conducta acosadora.<\/p>\n<p><strong>4. Te sientes descolocado<\/strong><\/p>\n<p>Si el inter\u00e9s de tu ex ha llegado demasiado lejos y te sientes aterrado, es importante analizar la situaci\u00f3n. Muller se\u00f1ala que si sientes miedo no lo ignores, pues algunas personas -especialmente los hombres- tienden a hacer caso omiso del acoso. \u201cPero puede ser peligroso, ya que no siempre sabes las intenciones finales de alguien\u201d, dice. Asimismo, no debes suponer que es normal o que es algo sin importancia.<\/p>\n<p>Es fundamental que hables el tema con alguien y si es necesario reportar la situaci\u00f3n a la polic\u00eda, sugiere el detective estadounidense y escritor Mike Proctor, ya que as\u00ed te sentir\u00e1s un poco m\u00e1s protegido y habr\u00e1 constancia de la situaci\u00f3n.<\/p>\n<p>La psic\u00f3loga espa\u00f1ola Soraya Campos se\u00f1al\u00f3 al sitio de tendencia En Plenitud, que \u201clo recomendable es nunca contradecir lo que uno se ha pautado por miedo a la agresividad de la ex pareja o porque se cree que cediendo un poco dejar\u00e1 de molestar, porque a partir de ese momento, si se regala terreno se estar\u00e1 empezando a perder la compostura, la calma y se entrar\u00e1 en un juego obsesivo y compulsivo del que es muy dif\u00edcil librarse\u201d.<\/p>\n<p><strong>Fuente:<\/strong> <a href=\"http:\/\/www.biobiochile.cl\/2014\/10\/21\/que-hacer-cuando-una-ex-pareja-no-te-deja-en-paz.shtml\">BioBioChile<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Aunque es halagador que alguien se interese en ti, cuando esa persona sobrepasa los l\u00edmites e invade tu espacio personal, la situaci\u00f3n puede volverse aterradora. Especialmente, cuando se trata de una ex pareja o una persona con la que saliste.<\/p>\n","protected":false},"author":3,"featured_media":9707,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-9706","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/9706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=9706"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/9706\/revisions"}],"predecessor-version":[{"id":9708,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/9706\/revisions\/9708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/9707"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=9706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=9706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=9706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}