{"id":97061,"date":"2024-06-29T07:38:19","date_gmt":"2024-06-29T11:38:19","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=97061"},"modified":"2024-06-29T07:38:45","modified_gmt":"2024-06-29T11:38:45","slug":"malaria-aumenta-y-se-registran-nuevos-casos-en-san-juan","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/malaria-aumenta-y-se-registran-nuevos-casos-en-san-juan\/","title":{"rendered":"Malaria aumenta y se registran nuevos casos en San Juan"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/667f545f946fa.jpeg\" alt=\"\" class=\"wp-image-97062\" width=\"201\" height=\"151\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/667f545f946fa.jpeg 800w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/667f545f946fa-300x226.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/667f545f946fa-768x578.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/667f545f946fa-600x452.jpeg 600w\" sizes=\"auto, (max-width: 201px) 100vw, 201px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Luego de que hasta la semana epidemiol\u00f3gica 23 se registrara un acumulado de 440 casos de malaria, el Ministerio de Salud P\u00fablica confirm\u00f3 el hallazgo de 12 casos de la enfermedad, tambi\u00e9n llamada \u201cpaludismo\u201d, que se transmite por la picadura de un mosquito infectado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con el bolet\u00edn epidemiol\u00f3gico de esta semana, correspondiente al n\u00famero 24, la Direcci\u00f3n nacional de Epidemiolog\u00eda indic\u00f3 que por la enfermedad ya hay un total acumulado de 452 casos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La entidad indic\u00f3 que estos 12 nuevos casos proceden de un solo lugar, la provincia San Juan; sin embargo, distribuidos en diferentes sectores de la demarcaci\u00f3n, siendo los de mayor proporci\u00f3n Pueblo Nuevo y Mijo-kil\u00f3metro 13.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, dijeron a trav\u00e9s de una misiva que en la actualidad no se han notificado muertes por malaria y que la incidencia acumulada es de 9.18.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las principales manifestaciones de la enfermedad son fiebre y un malestar similar al de la gripe, con escalofr\u00edos, dolor de cabeza, muscular y cansancio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para la semana 23, el doctor Ronald Skewes, director de epidemiolog\u00eda del Ministerio de Salud, hab\u00eda explicado que de los 440 registrados, unos 290 eran de Azua y 118 de San Juan, y estaban dados en esos focos por \u201clos trabajadores migrantes que vienen a trabajar la cosecha, ya sea tomate, habichuelas, etc\u00e9tera, en esas zonas\u201d.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">FUMIGACI\u00d3N<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La instituci\u00f3n dijo que a trav\u00e9s de las Direcciones Provinciales y \u00c1reas de Salud est\u00e1 fumigando en las comunidades afectadas, como parte de las estrategias de control, para \u201cevitar que siga la propagaci\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, hizo un llamado a la poblaci\u00f3n a que acuda al centro de salud m\u00e1s cercano si siente s\u00edntomas como, fiebre, dolor de cabeza y musculares y fatiga, \u201cya que la atenci\u00f3n oportuna contribuye a evitar casos graves\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los expertos recomiendan atenderla a tiempo. Adem\u00e1s, instaron a la ciudadan\u00eda a mantener su entorno libre de criaderos de mosquitos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otras enfermedades<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La entidad dijo que hay un total acumulado de 895 casos de dengue.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n notific\u00f3 tres casos sospechosos de Leptospirosis, para un total de 279, en lo que va de a\u00f1o. Estos casos son de hombres entre los 30 y 49 a\u00f1os, dos de los cuales se dedican al trabajo agr\u00edcola, de acuerdo con la entidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras que fueron reportados 784 nuevos casos de Covid-19, siendo el Distrito Nacional es la demarcaci\u00f3n que mayor cantidad de casos tiene, con un total de 245 en esta \u00faltima semana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Incide la concentraci\u00f3n del polvo del desierto del Sahara y la ola de calor agudizan los problemas respiratorios y las alergias, por lo que los especialistas recomiendan a las personas vulnerables adoptar medidas de higiene en el hogar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luego de que hasta la semana epidemiol\u00f3gica 23 se registrara un acumulado de 440 casos de malaria, el Ministerio de Salud P\u00fablica confirm\u00f3 el hallazgo de 12 casos de la enfermedad, tambi\u00e9n llamada \u201cpaludismo\u201d, que se transmite por la picadura de un mosquito infectado. De acuerdo con el bolet\u00edn epidemiol\u00f3gico de esta semana, correspondiente al n\u00famero 24, la Direcci\u00f3n nacional de Epidemiolog\u00eda indic\u00f3 que por la enfermedad ya hay un total acumulado de 452 casos. La entidad indic\u00f3 que estos 12 nuevos casos proceden de un solo lugar, la provincia San Juan; sin embargo, distribuidos en diferentes sectores de la demarcaci\u00f3n, siendo los de mayor proporci\u00f3n Pueblo Nuevo y Mijo-kil\u00f3metro 13. Asimismo, dijeron a trav\u00e9s de una misiva que en la actualidad no se han notificado muertes por malaria y que la incidencia acumulada es de 9.18. Las principales manifestaciones de la enfermedad son fiebre y un malestar similar al de la gripe, con escalofr\u00edos, dolor de cabeza, muscular y cansancio. Para la semana 23, el doctor Ronald Skewes, director de epidemiolog\u00eda del Ministerio de Salud, hab\u00eda explicado que de los 440 registrados, unos 290 eran de Azua y 118 de San Juan, y estaban dados en esos focos por \u201clos trabajadores migrantes que vienen a trabajar la cosecha, ya sea tomate, habichuelas, etc\u00e9tera, en esas zonas\u201d. FUMIGACI\u00d3N La instituci\u00f3n dijo que a trav\u00e9s de las Direcciones Provinciales y \u00c1reas de Salud est\u00e1 fumigando en las comunidades afectadas, como parte de las estrategias de control, para \u201cevitar que siga la propagaci\u00f3n\u201d. Adem\u00e1s, hizo un llamado a la poblaci\u00f3n a que acuda al centro de salud m\u00e1s cercano si siente s\u00edntomas como, fiebre, dolor de cabeza y musculares y fatiga, \u201cya que la atenci\u00f3n oportuna contribuye a evitar casos graves\u201d. Los expertos recomiendan atenderla a tiempo. Adem\u00e1s, instaron a la ciudadan\u00eda a mantener su entorno libre de criaderos de mosquitos. Otras enfermedades La entidad dijo que hay un total acumulado de 895 casos de dengue. Tambi\u00e9n notific\u00f3 tres casos sospechosos de Leptospirosis, para un total de 279, en lo que va de a\u00f1o. Estos casos son de hombres entre los 30 y 49 a\u00f1os, dos de los cuales se dedican al trabajo agr\u00edcola, de acuerdo con la entidad. Mientras que fueron reportados 784 nuevos casos de Covid-19, siendo el Distrito Nacional es la demarcaci\u00f3n que mayor cantidad de casos tiene, con un total de 245 en esta \u00faltima semana. Incide la concentraci\u00f3n del polvo del desierto del Sahara y la ola de calor agudizan los problemas respiratorios y las alergias, por lo que los especialistas recomiendan a las personas vulnerables adoptar medidas de higiene en el hogar.<\/p>\n","protected":false},"author":9,"featured_media":97062,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-97061","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/97061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=97061"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/97061\/revisions"}],"predecessor-version":[{"id":97063,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/97061\/revisions\/97063"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/97062"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=97061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=97061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=97061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}