{"id":97068,"date":"2024-06-29T10:34:07","date_gmt":"2024-06-29T14:34:07","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=97068"},"modified":"2024-06-29T10:34:09","modified_gmt":"2024-06-29T14:34:09","slug":"empresa-de-puerto-rico-demanda-a-aerodom-por-incumplimiento-de-contrato","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/empresa-de-puerto-rico-demanda-a-aerodom-por-incumplimiento-de-contrato\/","title":{"rendered":"Empresa de Puerto Rico demanda a Aerodom por \u00abincumplimiento de contrato\u00bb"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/65de8cf708c1d.r_d.1221-600.jpeg\" alt=\"\" class=\"wp-image-97069\" width=\"241\" height=\"133\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/65de8cf708c1d.r_d.1221-600.jpeg 800w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/65de8cf708c1d.r_d.1221-600-300x166.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/65de8cf708c1d.r_d.1221-600-768x424.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/06\/65de8cf708c1d.r_d.1221-600-600x332.jpeg 600w\" sizes=\"auto, (max-width: 241px) 100vw, 241px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Aeropuertos Dominicanos Siglo XXI SA (Aerodom),<\/strong>&nbsp;perteneciente a la plataforma aeroportuaria mundial de Vinci Airports, fue objeto de una demanda por 8 millones de d\u00f3lares por parte de la empresa puertorrique\u00f1a Management&nbsp;<strong>Group Investors (MGI<\/strong>) por, supuestamente, incumplimiento de contrato e interferencia tortuosa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan el escrito, interpuesto ante el Tribunal de Estados Unidos para el Distrito de Puerto Rico el 24 de junio pasado, y al que tuvo acceso EFE este viernes, la compa\u00f1\u00eda demandante reclama 8 millones de d\u00f3lares en da\u00f1os y perjuicios a Aerodom, operador, administrador y explotador econ\u00f3mico de varios aeropuertos en Rep\u00fablica Dominicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La demanda alude a disputas relativas a diversos acuerdos relacionados con servicios de catering en varios aeropuertos dominicanos, donde la sociedad de responsabilidad limitada con sede en Carolina, Estados Unidos, opera concesiones de alimentos y bebidas a trav\u00e9s de su filial Inversiones Llers SRL (Llers).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos servicios se prestaban mediante dos contratos de subconcesi\u00f3n, uno para servicios en terminales, firmado en 2005, y otro para servicios de catering a bordo, firmado en 2021, acuerdos que se prorrogar\u00edan autom\u00e1ticamente si se extend\u00eda la concesi\u00f3n principal de Aerodom con el Gobierno dominicano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan el contenido de la demanda, la ampliaci\u00f3n del contrato entre las autoridades del pa\u00eds y la operadora, que gestiona varios aeropuertos en territorio dominicano, se produjo en noviembre de 2023 para extenderlo hasta marzo de 2060.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, MGI denuncia que Aerodom y Vinci han intentado limitar la extensi\u00f3n de los contratos de subconcesi\u00f3n a solo cinco a\u00f1os, contrariamente a los t\u00e9rminos acordados, algo que, seg\u00fan la empresa demandante constituye un incumplimiento del contrato y ha provocado \u00abperturbaciones econ\u00f3micas y operativas significativas\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los argumentos expuestos para sustentar la denuncia, MGI afirma que en 2020 la filial Llers inici\u00f3, a instancias de Aerodom y Vinci, \u00abimportantes inversiones\u00bb en los aeropuertos internacionales de Las Am\u00e9ricas y El Hig\u00fcero, ambos en Santo Domingo; el Gregorio Luper\u00f3n, en Puerto Plata (norte); el Mar\u00eda Montez, en Barahona (sur), y El Catey y Arroyo Barril en Saman\u00e1 (noreste).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre las inversiones, la demanda se\u00f1ala la construcci\u00f3n de una nueva cocina de catering a bordo en el Aeropuerto Las Am\u00e9ricas, que supuso el desembolso de m\u00e1s de 28 millones de d\u00f3lares, cuya construcci\u00f3n se complet\u00f3 el mayo y est\u00e1 previsto que est\u00e9 operativa en julio pr\u00f3ximo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan MGI, Aerodom y Vinci han impedido los preparativos para el inicio de operaciones en el nuevo catering a bordo, por lo que \u00abha tenido que desviar esfuerzos y recursos para garantizar la ejecuci\u00f3n de sus ampliaciones de contrato\u00bb, en un momento en el que estos esfuerzos y recursos \u00abdeber\u00edan centrarse en garantizar el inicio de operaciones de la nueva cocina a bordo seg\u00fan lo previsto\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos retrasos, \u00abtendr\u00edan un efecto adverso en las declaraciones, compromisos y acuerdos realizados por MGI con diferentes aerol\u00edneas\u00bb y, seg\u00fan reza el texto, \u00abha sufrido y puede sufrir da\u00f1os econ\u00f3micos y consecuencias en relaci\u00f3n con sus compromisos con terceros y da\u00f1o reputacional\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuestionado por EFE a este respecto, el equipo jur\u00eddico de Aerodom ha rehusado hacer \u00abcomentarios en este momento sobre ese proceso particular\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aeropuertos Dominicanos Siglo XXI SA (Aerodom),&nbsp;perteneciente a la plataforma aeroportuaria mundial de Vinci Airports, fue objeto de una demanda por 8 millones de d\u00f3lares por parte de la empresa puertorrique\u00f1a Management&nbsp;Group Investors (MGI) por, supuestamente, incumplimiento de contrato e interferencia tortuosa. Seg\u00fan el escrito, interpuesto ante el Tribunal de Estados Unidos para el Distrito de Puerto Rico el 24 de junio pasado, y al que tuvo acceso EFE este viernes, la compa\u00f1\u00eda demandante reclama 8 millones de d\u00f3lares en da\u00f1os y perjuicios a Aerodom, operador, administrador y explotador econ\u00f3mico de varios aeropuertos en Rep\u00fablica Dominicana. La demanda alude a disputas relativas a diversos acuerdos relacionados con servicios de catering en varios aeropuertos dominicanos, donde la sociedad de responsabilidad limitada con sede en Carolina, Estados Unidos, opera concesiones de alimentos y bebidas a trav\u00e9s de su filial Inversiones Llers SRL (Llers). Estos servicios se prestaban mediante dos contratos de subconcesi\u00f3n, uno para servicios en terminales, firmado en 2005, y otro para servicios de catering a bordo, firmado en 2021, acuerdos que se prorrogar\u00edan autom\u00e1ticamente si se extend\u00eda la concesi\u00f3n principal de Aerodom con el Gobierno dominicano. Seg\u00fan el contenido de la demanda, la ampliaci\u00f3n del contrato entre las autoridades del pa\u00eds y la operadora, que gestiona varios aeropuertos en territorio dominicano, se produjo en noviembre de 2023 para extenderlo hasta marzo de 2060. Sin embargo, MGI denuncia que Aerodom y Vinci han intentado limitar la extensi\u00f3n de los contratos de subconcesi\u00f3n a solo cinco a\u00f1os, contrariamente a los t\u00e9rminos acordados, algo que, seg\u00fan la empresa demandante constituye un incumplimiento del contrato y ha provocado \u00abperturbaciones econ\u00f3micas y operativas significativas\u00bb. Entre los argumentos expuestos para sustentar la denuncia, MGI afirma que en 2020 la filial Llers inici\u00f3, a instancias de Aerodom y Vinci, \u00abimportantes inversiones\u00bb en los aeropuertos internacionales de Las Am\u00e9ricas y El Hig\u00fcero, ambos en Santo Domingo; el Gregorio Luper\u00f3n, en Puerto Plata (norte); el Mar\u00eda Montez, en Barahona (sur), y El Catey y Arroyo Barril en Saman\u00e1 (noreste). Entre las inversiones, la demanda se\u00f1ala la construcci\u00f3n de una nueva cocina de catering a bordo en el Aeropuerto Las Am\u00e9ricas, que supuso el desembolso de m\u00e1s de 28 millones de d\u00f3lares, cuya construcci\u00f3n se complet\u00f3 el mayo y est\u00e1 previsto que est\u00e9 operativa en julio pr\u00f3ximo. Seg\u00fan MGI, Aerodom y Vinci han impedido los preparativos para el inicio de operaciones en el nuevo catering a bordo, por lo que \u00abha tenido que desviar esfuerzos y recursos para garantizar la ejecuci\u00f3n de sus ampliaciones de contrato\u00bb, en un momento en el que estos esfuerzos y recursos \u00abdeber\u00edan centrarse en garantizar el inicio de operaciones de la nueva cocina a bordo seg\u00fan lo previsto\u00bb. Estos retrasos, \u00abtendr\u00edan un efecto adverso en las declaraciones, compromisos y acuerdos realizados por MGI con diferentes aerol\u00edneas\u00bb y, seg\u00fan reza el texto, \u00abha sufrido y puede sufrir da\u00f1os econ\u00f3micos y consecuencias en relaci\u00f3n con sus compromisos con terceros y da\u00f1o reputacional\u00bb. Cuestionado por EFE a este respecto, el equipo jur\u00eddico de Aerodom ha rehusado hacer \u00abcomentarios en este momento sobre ese proceso particular\u00bb.<\/p>\n","protected":false},"author":9,"featured_media":97069,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[460],"tags":[],"class_list":["post-97068","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turismo-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/97068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=97068"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/97068\/revisions"}],"predecessor-version":[{"id":97070,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/97068\/revisions\/97070"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/97069"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=97068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=97068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=97068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}