{"id":97120,"date":"2024-07-02T19:25:10","date_gmt":"2024-07-02T23:25:10","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=97120"},"modified":"2024-07-02T19:25:12","modified_gmt":"2024-07-02T23:25:12","slug":"puerto-plata-pena-maxima-a-hombre-mato-otro-23-punaladas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/puerto-plata-pena-maxima-a-hombre-mato-otro-23-punaladas\/","title":{"rendered":"PUERTO PLATA: Pena m\u00e1xima a hombre mat\u00f3 otro 23 pu\u00f1aladas"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/07\/PALACIO-DE-JUSTICIA-DE-PUERTO-PLATA.jpg\" alt=\"\" class=\"wp-image-97121\" width=\"259\" height=\"137\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/07\/PALACIO-DE-JUSTICIA-DE-PUERTO-PLATA.jpg 693w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/07\/PALACIO-DE-JUSTICIA-DE-PUERTO-PLATA-300x160.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/07\/PALACIO-DE-JUSTICIA-DE-PUERTO-PLATA-600x320.jpg 600w\" sizes=\"auto, (max-width: 259px) 100vw, 259px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"> PUERTO PLATA , 2 jul (EFE).- El Tribunal Colegiado de Puerto Plata impuso una condena de 30 a\u00f1os de prisi\u00f3n contra un Alberto de Jes\u00fas G\u00f3mez, por el asesinato de Juan Alberto Sarita Pichardo, inform\u00f3 este martes la Procuradur\u00eda General de la Rep\u00fablica (PGR) en un comunicado.En la investigaci\u00f3n se determin\u00f3 que el incidente ocurri\u00f3 la noche del viernes 13 de mayo de 2022, en el sector Los Mameyes del municipio de Puerto Plata, cuando el imputado atac\u00f3 por la espalda a la v\u00edctima, \u00a0quien se encontraba en la calle hablando con una persona, propin\u00e1ndole 23 estocadas con un arma blanca que luego fue incautada las autoridades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La acusaci\u00f3n present\u00f3 pruebas concluyentes al Tribunal Colegiado, \u00abdemostrando la culpabilidad del imputado m\u00e1s all\u00e1 de toda duda razonable\u00bb, indic\u00f3 la PGR en la nota.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Ministerio P\u00fablico calific\u00f3 estos hechos como asesinato y uso ilegal de armas blancas, delitos tipificados en el C\u00f3digo Penal y la Ley para el Control y Regulaci\u00f3n de Armas, Municiones y Materiales Relacionados, respectivamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El tribunal dispuso que el imputado cumpla la condena en el Centro de Correcci\u00f3n y Rehabilitaci\u00f3n San Felipe de Puerto Plata.EFE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PUERTO PLATA , 2 jul (EFE).- El Tribunal Colegiado de Puerto Plata impuso una condena de 30 a\u00f1os de prisi\u00f3n contra un Alberto de Jes\u00fas G\u00f3mez, por el asesinato de Juan Alberto Sarita Pichardo, inform\u00f3 este martes la Procuradur\u00eda General de la Rep\u00fablica (PGR) en un comunicado.En la investigaci\u00f3n se determin\u00f3 que el incidente ocurri\u00f3 la noche del viernes 13 de mayo de 2022, en el sector Los Mameyes del municipio de Puerto Plata, cuando el imputado atac\u00f3 por la espalda a la v\u00edctima, \u00a0quien se encontraba en la calle hablando con una persona, propin\u00e1ndole 23 estocadas con un arma blanca que luego fue incautada las autoridades. La acusaci\u00f3n present\u00f3 pruebas concluyentes al Tribunal Colegiado, \u00abdemostrando la culpabilidad del imputado m\u00e1s all\u00e1 de toda duda razonable\u00bb, indic\u00f3 la PGR en la nota. El Ministerio P\u00fablico calific\u00f3 estos hechos como asesinato y uso ilegal de armas blancas, delitos tipificados en el C\u00f3digo Penal y la Ley para el Control y Regulaci\u00f3n de Armas, Municiones y Materiales Relacionados, respectivamente. El tribunal dispuso que el imputado cumpla la condena en el Centro de Correcci\u00f3n y Rehabilitaci\u00f3n San Felipe de Puerto Plata.EFE<\/p>\n","protected":false},"author":9,"featured_media":97121,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-97120","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/97120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=97120"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/97120\/revisions"}],"predecessor-version":[{"id":97122,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/97120\/revisions\/97122"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/97121"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=97120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=97120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=97120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}