{"id":97198,"date":"2024-07-07T09:23:35","date_gmt":"2024-07-07T13:23:35","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=97198"},"modified":"2024-07-07T09:23:37","modified_gmt":"2024-07-07T13:23:37","slug":"eeuu-encuesta-revela-michelle-obama-derrotaria-a-trump","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/eeuu-encuesta-revela-michelle-obama-derrotaria-a-trump\/","title":{"rendered":"EEUU: Encuesta revela Michelle Obama derrotar\u00eda a Trump"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/07\/mic.jpg\" alt=\"\" class=\"wp-image-97199\" width=\"230\" height=\"152\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/07\/mic.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/07\/mic-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/07\/mic-600x400.jpg 600w\" sizes=\"auto, (max-width: 230px) 100vw, 230px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">WASHINGTON.- La ex primera dama de EE. UU., Michelle Obama, es la \u00fanica dem\u00f3crata que podr\u00eda derrotar a Donald Trump en las elecciones presidenciales de noviembre, seg\u00fan revel\u00f3 una nueva encuesta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La encuesta, realizada por Reuters\/Ipsos, desvel\u00f3 que la ex primera dama cuenta con un 50 % de apoyo, y Trump con un 39 %. Esto la convierte en la \u00fanica dem\u00f3crata con ventaja sobre el expresidente en un hipot\u00e9tico enfrentamiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Solo un cuatro % de los consultados dijo que no votar\u00eda en las elecciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, el presidente Joe Biden y Trump, cada uno con un 40 % de aprobaci\u00f3n, quedar\u00edan parejos en una competencia cara a cara. Un 8 % de los participantes dijo que votar\u00eda por alguien m\u00e1s, y otro 8 % que no votar\u00eda por nadie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, la vicepresidenta Kamala Harris obtendr\u00eda un 42 % de los votos si se enfrentara a Trump, seg\u00fan revel\u00f3 la encuesta. Otros miembros del partido dem\u00f3crata presentados como posibles sustitutos de Biden incluyen al gobernador del estado de California Gavin Newsom (con un 3 % menos de aprobaci\u00f3n que Trump), y la gobernadora de Michigan Gretchen Whitmer (quien quedar\u00eda rezagada por un 5 %).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un sondeo anterior realizado por la encuestadora estadounidense\u00a0Rasmussen Report<a rel=\"noreferrer noopener\" href=\"https:\/\/www.rasmussenreports.com\/public_content\/politics\/biden_administration\/47_think_democrats_may_replace_biden_as_candidate\" target=\"_blank\">s<\/a>\u00a0y publicado en febrero, Michelle Obama tambi\u00e9n result\u00f3 ser la opci\u00f3n preferida entre los votantes dem\u00f3cratas para reemplazar a Biden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ex primera dama ha afirmado en varias ocasiones que no tiene planes de postularse a la presidencia. De hecho, lleg\u00f3 a decir lo siguiente en el a\u00f1o 2017, cuando finalizaba el segundo periodo presidencial de su esposo: \u201cNo, de ninguna manera. No voy a hacerlo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero en marzo se reavivaron las especulaciones sobre una posible postulaci\u00f3n, y especialmente sobre la posibilidad de que Biden la reclute como su pr\u00f3xima vicepresidenta, luego de que\u00a0la comentarista de CNN Alisyn Camerota sugeriera que deber\u00eda ser candidata al cargo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, Obama de nuevo rechaz\u00f3 los llamamientos\u00a0en una declaraci\u00f3n al canal NBC News. Asimismo, el expresidente de EE. UU. Barack Obama tambi\u00e9n desminti\u00f3 los rumores de que su esposa vaya a formar parte de la lista de candidatos dem\u00f3cratas. Afirm\u00f3: \u201cNo le gusta la pol\u00edtica\u201d y aclar\u00f3 que su esposa no ten\u00eda planes de postularse a la presidencia en el futuro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar del claro rechazo a la idea por parte de los Obama, varios usuarios de las redes sociales han expresado que apoyar\u00edan a la ex primera dama si participara en los comicios de 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cQuerida Michelle Obama: lo siento, pero debes postularte. No solo se trata de ti y tu familia. Somos muchos los que te necesitamos, hoy y en el futuro\u201d, expres\u00f3 otro usuario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMe gusta la idea de que Michelle Obama desaf\u00ede a Donald Trump. Sus posibilidades superan con mucho a las del viejo Biden\u201d, coment\u00f3 un tercero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras su desastroso desempe\u00f1o en el debate contra Trump la semana pasada (en el que por momentos parec\u00eda disperso e incluso pareci\u00f3 perder el hilo de su discurso), Biden se enfrenta a un creciente llamado a abandonar su candidatura, incluso desde su propio partido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El martes, el presidente se refiri\u00f3 a su mal desempe\u00f1o durante el debate y se lo atribuy\u00f3 al jet lag y a los viajes internacionales que realiz\u00f3 poco antes del evento. Sus asesores han dicho que se debi\u00f3 a un resfriado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, algunos dem\u00f3cratas no est\u00e1n convencidos. El representante de Texas Lloyd Doggett se convirti\u00f3 en el primer legislador dem\u00f3crata en funciones en pedir p\u00fablicamente que Biden que abandone la candidatura. Asimismo, el exrepresentante de Ohio Tim Ryan escribi\u00f3 en un art\u00edculo publicado en&nbsp;<em>Newsweek<\/em>&nbsp;que Harris era la mejor opci\u00f3n para el partido de cara al futuro; y calific\u00f3 de pocos realistas a quienes consideran que \u201cel Joe Biden que vimos en el debate y que seguiremos viendo\u201d tiene m\u00e1s posibilidades de derrotar a Trump que Harris.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al igual que Obama, los asesores de Harris han rechazado la propuesta de una candidatura que no incluya a Biden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa vicepresidenta Harris espera poder cumplir un segundo t\u00e9rmino junto al presidente Joe Biden\u201d, expres\u00f3 un comunicado oficial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, tanto Newsom como Whitmer tambi\u00e9n han descartado la posibilidad de reemplazar a Biden en la candidatura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un correo electr\u00f3nico que inclu\u00eda un enlace al portal de recaudaci\u00f3n de fondos para la campa\u00f1a de Biden, el gobernador de California calific\u00f3 estas especulaciones de \u201cinnecesarias y de poca utilidad\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNo vamos a darle la espalda solo por un debate fallido. \u00bfQu\u00e9 clase de partido hace algo as\u00ed?, escribi\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El secretario de transporte Pete Buttigieg, el gobernador de Maryland Wes Moore y el gobernador de Illinois J. B. Pritzker tambi\u00e9n han sido mencionados como posibles candidatos sustitutos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>WASHINGTON.- La ex primera dama de EE. UU., Michelle Obama, es la \u00fanica dem\u00f3crata que podr\u00eda derrotar a Donald Trump en las elecciones presidenciales de noviembre, seg\u00fan revel\u00f3 una nueva encuesta. La encuesta, realizada por Reuters\/Ipsos, desvel\u00f3 que la ex primera dama cuenta con un 50 % de apoyo, y Trump con un 39 %. Esto la convierte en la \u00fanica dem\u00f3crata con ventaja sobre el expresidente en un hipot\u00e9tico enfrentamiento. Solo un cuatro % de los consultados dijo que no votar\u00eda en las elecciones. Por otro lado, el presidente Joe Biden y Trump, cada uno con un 40 % de aprobaci\u00f3n, quedar\u00edan parejos en una competencia cara a cara. Un 8 % de los participantes dijo que votar\u00eda por alguien m\u00e1s, y otro 8 % que no votar\u00eda por nadie. Asimismo, la vicepresidenta Kamala Harris obtendr\u00eda un 42 % de los votos si se enfrentara a Trump, seg\u00fan revel\u00f3 la encuesta. Otros miembros del partido dem\u00f3crata presentados como posibles sustitutos de Biden incluyen al gobernador del estado de California Gavin Newsom (con un 3 % menos de aprobaci\u00f3n que Trump), y la gobernadora de Michigan Gretchen Whitmer (quien quedar\u00eda rezagada por un 5 %). En un sondeo anterior realizado por la encuestadora estadounidense\u00a0Rasmussen Reports\u00a0y publicado en febrero, Michelle Obama tambi\u00e9n result\u00f3 ser la opci\u00f3n preferida entre los votantes dem\u00f3cratas para reemplazar a Biden. La ex primera dama ha afirmado en varias ocasiones que no tiene planes de postularse a la presidencia. De hecho, lleg\u00f3 a decir lo siguiente en el a\u00f1o 2017, cuando finalizaba el segundo periodo presidencial de su esposo: \u201cNo, de ninguna manera. No voy a hacerlo\u201d. Pero en marzo se reavivaron las especulaciones sobre una posible postulaci\u00f3n, y especialmente sobre la posibilidad de que Biden la reclute como su pr\u00f3xima vicepresidenta, luego de que\u00a0la comentarista de CNN Alisyn Camerota sugeriera que deber\u00eda ser candidata al cargo. Sin embargo, Obama de nuevo rechaz\u00f3 los llamamientos\u00a0en una declaraci\u00f3n al canal NBC News. Asimismo, el expresidente de EE. UU. Barack Obama tambi\u00e9n desminti\u00f3 los rumores de que su esposa vaya a formar parte de la lista de candidatos dem\u00f3cratas. Afirm\u00f3: \u201cNo le gusta la pol\u00edtica\u201d y aclar\u00f3 que su esposa no ten\u00eda planes de postularse a la presidencia en el futuro. A pesar del claro rechazo a la idea por parte de los Obama, varios usuarios de las redes sociales han expresado que apoyar\u00edan a la ex primera dama si participara en los comicios de 2024. \u201cQuerida Michelle Obama: lo siento, pero debes postularte. No solo se trata de ti y tu familia. Somos muchos los que te necesitamos, hoy y en el futuro\u201d, expres\u00f3 otro usuario. \u201cMe gusta la idea de que Michelle Obama desaf\u00ede a Donald Trump. Sus posibilidades superan con mucho a las del viejo Biden\u201d, coment\u00f3 un tercero. Tras su desastroso desempe\u00f1o en el debate contra Trump la semana pasada (en el que por momentos parec\u00eda disperso e incluso pareci\u00f3 perder el hilo de su discurso), Biden se enfrenta a un creciente llamado a abandonar su candidatura, incluso desde su propio partido. El martes, el presidente se refiri\u00f3 a su mal desempe\u00f1o durante el debate y se lo atribuy\u00f3 al jet lag y a los viajes internacionales que realiz\u00f3 poco antes del evento. Sus asesores han dicho que se debi\u00f3 a un resfriado. Sin embargo, algunos dem\u00f3cratas no est\u00e1n convencidos. El representante de Texas Lloyd Doggett se convirti\u00f3 en el primer legislador dem\u00f3crata en funciones en pedir p\u00fablicamente que Biden que abandone la candidatura. Asimismo, el exrepresentante de Ohio Tim Ryan escribi\u00f3 en un art\u00edculo publicado en&nbsp;Newsweek&nbsp;que Harris era la mejor opci\u00f3n para el partido de cara al futuro; y calific\u00f3 de pocos realistas a quienes consideran que \u201cel Joe Biden que vimos en el debate y que seguiremos viendo\u201d tiene m\u00e1s posibilidades de derrotar a Trump que Harris. Al igual que Obama, los asesores de Harris han rechazado la propuesta de una candidatura que no incluya a Biden. \u201cLa vicepresidenta Harris espera poder cumplir un segundo t\u00e9rmino junto al presidente Joe Biden\u201d, expres\u00f3 un comunicado oficial. Por otro lado, tanto Newsom como Whitmer tambi\u00e9n han descartado la posibilidad de reemplazar a Biden en la candidatura. En un correo electr\u00f3nico que inclu\u00eda un enlace al portal de recaudaci\u00f3n de fondos para la campa\u00f1a de Biden, el gobernador de California calific\u00f3 estas especulaciones de \u201cinnecesarias y de poca utilidad\u201d. \u201cNo vamos a darle la espalda solo por un debate fallido. \u00bfQu\u00e9 clase de partido hace algo as\u00ed?, escribi\u00f3. El secretario de transporte Pete Buttigieg, el gobernador de Maryland Wes Moore y el gobernador de Illinois J. B. Pritzker tambi\u00e9n han sido mencionados como posibles candidatos sustitutos.<\/p>\n","protected":false},"author":9,"featured_media":97199,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-97198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/97198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=97198"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/97198\/revisions"}],"predecessor-version":[{"id":97200,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/97198\/revisions\/97200"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/97199"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=97198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=97198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=97198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}