{"id":97814,"date":"2024-07-30T08:55:22","date_gmt":"2024-07-30T12:55:22","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=97814"},"modified":"2024-08-13T11:26:35","modified_gmt":"2024-08-13T15:26:35","slug":"35va-aniversario-parada-dominicana-en-el-bronx-2024","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/35va-aniversario-parada-dominicana-en-el-bronx-2024\/","title":{"rendered":"35va Aniversario Parada Dominicana en el Bronx 2024"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/07\/parada-Dominicana-en-el-Bronx-202463-1024x576.jpg\" alt=\"\" class=\"wp-image-97827\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/07\/parada-Dominicana-en-el-Bronx-202463-1024x576.jpg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/07\/parada-Dominicana-en-el-Bronx-202463-300x169.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/07\/parada-Dominicana-en-el-Bronx-202463-768x432.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/07\/parada-Dominicana-en-el-Bronx-202463-600x338.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/07\/parada-Dominicana-en-el-Bronx-202463.jpg 1365w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El montaje, nunca antes visto, se inici\u00f3 en Forhand hasta la 171 de la larga avenida, que con sus ocho carriles ocupados, provoc\u00f3 trastornos para normalizar el transito de la ciudad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los colores de los s\u00edmbolos patrios, la alegr\u00eda, el entusiasmo, lo aut\u00f3ctono, el orgullo dominicano y la asistencia, superaron las expectativas y el esplendor de eventos anteriores en el desfile para celebrar los 35 a\u00f1os de La Gran Parada del Bronx, que se llev\u00f3 cabo en la avenida Grand Concorse de Nueva York.<\/p>\n\n\n\n[Best_Wordpress_Gallery id=\u00bb9&#8243; gal_title=\u00bbParada Dominicana en Bronx 2024&#8243;]\n\n\n\n<p class=\"wp-block-paragraph\">Con la presencia de m\u00e1s de 2,000 agentes policiales, ciento de miles de personas desafiaron las altas temperaturas del verano para darse un verdadero ba\u00f1o de dominicanidad. El evento se desarroll\u00f3, sin incidentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El montaje, nunca antes visto, se inici\u00f3 en Forhand hasta la 171 de la larga avenida, que con sus ocho carriles ocupados, provoc\u00f3 trastornos para normalizar el transito de la ciudad, lo que gener\u00f3 entaponamiento hacia esta \u00e1rea, en adici\u00f3n a los retrasos en el transporte del fin de semana, inclu\u00eddo los trenes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Casi un centenar de comparsas e igual n\u00famero de representaciones de diversas expresiones, entidades que ten\u00edan en com\u00fan el orgullo patrio, mostraron la alegr\u00eda que caracteriza la di\u00e1spora criolla, dejando muy clara su influencia en la gran urbe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante m\u00e1s de seis horas, la algarab\u00eda se apoder\u00f3 de la v\u00eda, tanto en la m\u00fasica, que cambiaba cada un metro, debido a los tantos equipos de sonido, como los colores, bullas, gritos y manifestaciones de alegr\u00eda, que le son propias a los dominicanos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"835\" height=\"540\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/08\/agua-premium.jpg\" alt=\"\" class=\"wp-image-98293\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/08\/agua-premium.jpg 835w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/08\/agua-premium-300x194.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/08\/agua-premium-768x497.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/08\/agua-premium-600x388.jpg 600w\" sizes=\"auto, (max-width: 835px) 100vw, 835px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Un efectivo operativo policial coordinado con mucha antelaci\u00f3n, logr\u00f3 los resultados, tal y como advirti\u00f3 Felipe Febles, director y fundador de La Gran Parada del Bronx, quien agradeci\u00f3 el rotundo \u00e9xito y la acogida, que super\u00f3, las anteriores. La celebraci\u00f3n del 35 Aniversario de La Gran Parada Dominicana del Bronx, reuni\u00f3 este domingo 28 de julio la mayor cantidad de latinos en toda su historia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde las 10:00 de la ma\u00f1ana en la avenida Grand Concourse en el Bronx se consolid\u00f3 como la celebraci\u00f3n m\u00e1s grande y significativa de la comunidad dominicana en Estados Unidos, la cual puso de manifiesto la cultura, la m\u00fasica, los emblemas y s\u00edmbolos dominicanos, una forma de reafirmar el compromiso con el bienestar y el progreso de la comunidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El montaje, nunca antes visto, se inici\u00f3 en Forhand hasta la 171 de la larga avenida, que con sus ocho carriles ocupados, provoc\u00f3 trastornos para normalizar el transito de la ciudad. Los colores de los s\u00edmbolos patrios, la alegr\u00eda, el entusiasmo, lo aut\u00f3ctono, el orgullo dominicano y la asistencia, superaron las expectativas y el esplendor de eventos anteriores en el desfile para celebrar los 35 a\u00f1os de La Gran Parada del Bronx, que se llev\u00f3 cabo en la avenida Grand Concorse de Nueva York. Con la presencia de m\u00e1s de 2,000 agentes policiales, ciento de miles de personas desafiaron las altas temperaturas del verano para darse un verdadero ba\u00f1o de dominicanidad. El evento se desarroll\u00f3, sin incidentes. El montaje, nunca antes visto, se inici\u00f3 en Forhand hasta la 171 de la larga avenida, que con sus ocho carriles ocupados, provoc\u00f3 trastornos para normalizar el transito de la ciudad, lo que gener\u00f3 entaponamiento hacia esta \u00e1rea, en adici\u00f3n a los retrasos en el transporte del fin de semana, inclu\u00eddo los trenes. Casi un centenar de comparsas e igual n\u00famero de representaciones de diversas expresiones, entidades que ten\u00edan en com\u00fan el orgullo patrio, mostraron la alegr\u00eda que caracteriza la di\u00e1spora criolla, dejando muy clara su influencia en la gran urbe. Durante m\u00e1s de seis horas, la algarab\u00eda se apoder\u00f3 de la v\u00eda, tanto en la m\u00fasica, que cambiaba cada un metro, debido a los tantos equipos de sonido, como los colores, bullas, gritos y manifestaciones de alegr\u00eda, que le son propias a los dominicanos. Un efectivo operativo policial coordinado con mucha antelaci\u00f3n, logr\u00f3 los resultados, tal y como advirti\u00f3 Felipe Febles, director y fundador de La Gran Parada del Bronx, quien agradeci\u00f3 el rotundo \u00e9xito y la acogida, que super\u00f3, las anteriores. La celebraci\u00f3n del 35 Aniversario de La Gran Parada Dominicana del Bronx, reuni\u00f3 este domingo 28 de julio la mayor cantidad de latinos en toda su historia. Desde las 10:00 de la ma\u00f1ana en la avenida Grand Concourse en el Bronx se consolid\u00f3 como la celebraci\u00f3n m\u00e1s grande y significativa de la comunidad dominicana en Estados Unidos, la cual puso de manifiesto la cultura, la m\u00fasica, los emblemas y s\u00edmbolos dominicanos, una forma de reafirmar el compromiso con el bienestar y el progreso de la comunidad.<\/p>\n","protected":false},"author":12,"featured_media":97890,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-97814","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sosua-en-el-mundo"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/97814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=97814"}],"version-history":[{"count":3,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/97814\/revisions"}],"predecessor-version":[{"id":98632,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/97814\/revisions\/98632"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/97890"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=97814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=97814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=97814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}