{"id":98035,"date":"2024-08-01T08:01:49","date_gmt":"2024-08-01T12:01:49","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=98035"},"modified":"2024-08-01T08:02:06","modified_gmt":"2024-08-01T12:02:06","slug":"jefe-oea-pide-tpi-impute-y-emita-orden-arresto-de-maduro","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/jefe-oea-pide-tpi-impute-y-emita-orden-arresto-de-maduro\/","title":{"rendered":"Jefe OEA pide TPI impute y emita orden arresto de Maduro"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/08\/almagroo70520-1024x546.jpg\" alt=\"\" class=\"wp-image-98036\" width=\"224\" height=\"119\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/08\/almagroo70520-1024x546.jpg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/08\/almagroo70520-300x160.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/08\/almagroo70520-768x409.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/08\/almagroo70520-600x320.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/08\/almagroo70520.jpg 1280w\" sizes=\"auto, (max-width: 224px) 100vw, 224px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">WASHINGTON, 1 Ago. (EUROPA PRESS) \u2013&nbsp;El secretario general de la Organizaci\u00f3n de Estados Americanos (OEA), Luis Almagro, ha pedido este mi\u00e9rcoles al Tribunal Penal Internacional (TPI) que impute al presidente de Venezuela, Nicol\u00e1s Maduro, y emita una orden de arresto en su contra por \u00abpremeditaci\u00f3n, alevos\u00eda, impulso brutal ferocidad, ventaja superior\u00bb en la represi\u00f3n de las protestas contra el chavismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abMaduro prometi\u00f3 un ba\u00f1o de sangre, y nos indign\u00f3 o\u00edrlo y m\u00e1s nos indigna ahora que lo est\u00e1 haciendo. Hay premeditaci\u00f3n, alevos\u00eda, impulso brutal ferocidad, ventaja superior. Es el momento de presentar cargos de imputaci\u00f3n y orden de captura por parte del Tribunal Penal Internacional contra los principales responsables, incluido Maduro. Es hora de la justicia\u00bb, ha expresado Almagro en&nbsp; la red social X.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese sentido, ha prometido que la OEA se har\u00e1 cargo de hacer la solicitud de estos cargos, aunque no ha especificado cu\u00e1les, tras lo que ha a\u00f1adido: \u00abPor un hemisferio libre de cr\u00edmenes de lesa humanidad\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este mi\u00e9rcoles el Consejo Permanente de la OEA conoci\u00f3 el caso de Venezuela pero sus miembros no lograron ponerse de acuerdo&nbsp; para emitir una resoluci\u00f3n conjunta con el objetivo de exigir al gobierno de este pa\u00eds la publicaci\u00f3n de las actas electorales, despu\u00e9s de que los resultados del Consejo Nacional Electoral (CNE) diesen la victoria Maduro, que la oposici\u00f3n ha rechazado tras denunciar un fraude.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La votaci\u00f3n se ha saldado con 17 votos a favor, once abstenciones \u2013entre las que destacan las de Bolivia, Brasil y Colombia\u2013, cero en contra y la ausencia de cinco pa\u00edses \u2013entre ellos M\u00e9xico y Venezuela\u2013, si bien es necesario lograr una mayor\u00eda absoluta para aprobar el texto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En disturbios escenificados en Venezuela en protesta por dicha proclamaci\u00f3n once manifestantes han resultado&nbsp; muertos y m\u00e1s de 1.000 detenidos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>WASHINGTON, 1 Ago. (EUROPA PRESS) \u2013&nbsp;El secretario general de la Organizaci\u00f3n de Estados Americanos (OEA), Luis Almagro, ha pedido este mi\u00e9rcoles al Tribunal Penal Internacional (TPI) que impute al presidente de Venezuela, Nicol\u00e1s Maduro, y emita una orden de arresto en su contra por \u00abpremeditaci\u00f3n, alevos\u00eda, impulso brutal ferocidad, ventaja superior\u00bb en la represi\u00f3n de las protestas contra el chavismo. \u00abMaduro prometi\u00f3 un ba\u00f1o de sangre, y nos indign\u00f3 o\u00edrlo y m\u00e1s nos indigna ahora que lo est\u00e1 haciendo. Hay premeditaci\u00f3n, alevos\u00eda, impulso brutal ferocidad, ventaja superior. Es el momento de presentar cargos de imputaci\u00f3n y orden de captura por parte del Tribunal Penal Internacional contra los principales responsables, incluido Maduro. Es hora de la justicia\u00bb, ha expresado Almagro en&nbsp; la red social X. En ese sentido, ha prometido que la OEA se har\u00e1 cargo de hacer la solicitud de estos cargos, aunque no ha especificado cu\u00e1les, tras lo que ha a\u00f1adido: \u00abPor un hemisferio libre de cr\u00edmenes de lesa humanidad\u00bb. Este mi\u00e9rcoles el Consejo Permanente de la OEA conoci\u00f3 el caso de Venezuela pero sus miembros no lograron ponerse de acuerdo&nbsp; para emitir una resoluci\u00f3n conjunta con el objetivo de exigir al gobierno de este pa\u00eds la publicaci\u00f3n de las actas electorales, despu\u00e9s de que los resultados del Consejo Nacional Electoral (CNE) diesen la victoria Maduro, que la oposici\u00f3n ha rechazado tras denunciar un fraude. La votaci\u00f3n se ha saldado con 17 votos a favor, once abstenciones \u2013entre las que destacan las de Bolivia, Brasil y Colombia\u2013, cero en contra y la ausencia de cinco pa\u00edses \u2013entre ellos M\u00e9xico y Venezuela\u2013, si bien es necesario lograr una mayor\u00eda absoluta para aprobar el texto. En disturbios escenificados en Venezuela en protesta por dicha proclamaci\u00f3n once manifestantes han resultado&nbsp; muertos y m\u00e1s de 1.000 detenidos.<\/p>\n","protected":false},"author":9,"featured_media":98036,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-98035","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/98035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=98035"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/98035\/revisions"}],"predecessor-version":[{"id":98037,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/98035\/revisions\/98037"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/98036"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=98035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=98035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=98035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}