{"id":98580,"date":"2024-08-12T07:20:11","date_gmt":"2024-08-12T11:20:11","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=98580"},"modified":"2024-08-12T07:20:19","modified_gmt":"2024-08-12T11:20:19","slug":"indomet-comunica-sobre-formacion-del-potencial-ciclon-tropical-numero-cinco","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/indomet-comunica-sobre-formacion-del-potencial-ciclon-tropical-numero-cinco\/","title":{"rendered":"Indomet comunica sobre formaci\u00f3n del potencial cicl\u00f3n tropical n\u00famero \u00abcinco\u00bb"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/08\/66a8e849178b3.jpeg\" alt=\"\" class=\"wp-image-98581\" width=\"242\" height=\"161\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/08\/66a8e849178b3.jpeg 800w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/08\/66a8e849178b3-300x200.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/08\/66a8e849178b3-768x513.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/08\/66a8e849178b3-600x401.jpeg 600w\" sizes=\"auto, (max-width: 242px) 100vw, 242px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El&nbsp;Instituto Dominicano de Meteorolog\u00eda (Indomet) confirm\u00f3 este domingo la formaci\u00f3n del potencial cicl\u00f3n tropical n\u00famero \u00abcinco\u00bb de esta temporada cicl\u00f3nica.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Indomet dijo que est\u00e1 localizado aproximadamente a unos 1,530 kil\u00f3metros este\/sureste de Antigua, y posee vientos m\u00e1ximos sostenidos de 45 kil\u00f3metros por hora (kph) y se mueve hacia el oeste\/noroeste a unos 33 kph.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abRecomendamos estar muy atentos al desplazamiento y evoluci\u00f3n de este sistema meteorol\u00f3gico tropical\u00bb, alert\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las precipitaciones continuar\u00e1n extendi\u00e9ndose de forma gradual durante el trascurso de la tarde y primeras horas de la noche hacia otras regiones del pa\u00eds, siendo las mismas m\u00e1s frecuentes y un poco m\u00e1s intensas en diferentes municipios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los municipios se encuentran: La Romana, San Pedro de Macor\u00eds, Duarte, Mar\u00eda Trinidad S\u00e1nchez, Saman\u00e1, Santiago, S\u00e1nchez Ram\u00edrez, La Vega, Monse\u00f1or Nouel, San Crist\u00f3bal, Monte Plata, Dajabon, Valverde, Santiago Rodr\u00edguez, San Juan y El\u00edas Pi\u00f1a, entre otras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El&nbsp;Instituto Dominicano de Meteorolog\u00eda (Indomet) confirm\u00f3 este domingo la formaci\u00f3n del potencial cicl\u00f3n tropical n\u00famero \u00abcinco\u00bb de esta temporada cicl\u00f3nica.&nbsp; El Indomet dijo que est\u00e1 localizado aproximadamente a unos 1,530 kil\u00f3metros este\/sureste de Antigua, y posee vientos m\u00e1ximos sostenidos de 45 kil\u00f3metros por hora (kph) y se mueve hacia el oeste\/noroeste a unos 33 kph. \u00abRecomendamos estar muy atentos al desplazamiento y evoluci\u00f3n de este sistema meteorol\u00f3gico tropical\u00bb, alert\u00f3. Las precipitaciones continuar\u00e1n extendi\u00e9ndose de forma gradual durante el trascurso de la tarde y primeras horas de la noche hacia otras regiones del pa\u00eds, siendo las mismas m\u00e1s frecuentes y un poco m\u00e1s intensas en diferentes municipios. Entre los municipios se encuentran: La Romana, San Pedro de Macor\u00eds, Duarte, Mar\u00eda Trinidad S\u00e1nchez, Saman\u00e1, Santiago, S\u00e1nchez Ram\u00edrez, La Vega, Monse\u00f1or Nouel, San Crist\u00f3bal, Monte Plata, Dajabon, Valverde, Santiago Rodr\u00edguez, San Juan y El\u00edas Pi\u00f1a, entre otras.<\/p>\n","protected":false},"author":9,"featured_media":98581,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-98580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/98580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=98580"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/98580\/revisions"}],"predecessor-version":[{"id":98582,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/98580\/revisions\/98582"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/98581"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=98580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=98580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=98580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}