{"id":98921,"date":"2024-08-30T07:08:57","date_gmt":"2024-08-30T11:08:57","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=98921"},"modified":"2024-08-30T07:08:58","modified_gmt":"2024-08-30T11:08:58","slug":"medico-de-rd-crea-nueva-tecnica-para-tratamiento-cardiovascular","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/medico-de-rd-crea-nueva-tecnica-para-tratamiento-cardiovascular\/","title":{"rendered":"M\u00e9dico de RD crea nueva t\u00e9cnica para tratamiento cardiovascular"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/08\/Foto-DR.-Licurgo-Cruz-con-su-tecnica-300x200-1.jpg\" alt=\"\" class=\"wp-image-98922\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SANTO DOMINGO.-&nbsp;<\/strong>El cardi\u00f3logo dominicano Licurgo Cruz cre\u00f3 una nueva t\u00e9cnica que evita complicaciones tras la colocaci\u00f3n de un stent coronario, utilizado para&nbsp;asegurar un&nbsp;flujo&nbsp;sangu\u00edneo adecuado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El stent previene problemas cardiovasculares, como infarto al miocardio o angina de pecho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas dolencias est\u00e1n entre las principales causas de muerte en Rep\u00fablica Dominicana. Datos recientes reportan por esa causa unos 30 mil fallecimientos anuales, (35 por ciento de los ocurridos en el pa\u00eds).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La aplicaci\u00f3n de la t\u00e9cnica del doctor Cruz se utiliza cuando ocurre la&nbsp;&nbsp;Re Estenosis Intra Stent (RIS), dificultad generada por el crecimiento de tejido dentro del stent, lo cual limita de nuevo el flujo sangu\u00edneo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LA \u00a8JACOBS TECHNIQUE\u00a8<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante ese evento derivado de la colocaci\u00f3n del stent coronario, los pacientes podr\u00edan padecer s\u00edntomas como dolor en el pecho, dificultad para respirar e incluso nuevos ataques card\u00edacos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cruz, cardi\u00f3logo hemodinamista que ofrece servicios especializados en el Hospital Metropolitano de Santiago (HOMS), es gobernador del Cap\u00edtulo Dominicano del Colegio Americano de Cardiolog\u00eda (ACC).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan explic\u00f3, la t\u00e9cnica nombrada \u201cJacobs Technique\u201d se utiliza dentro de un procedimiento y se puede estandarizar a nivel nacional y global.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEsta t\u00e9cnica, asegur\u00f3, facilitar\u00e1 el tratamiento de la RIS e impactar\u00e1 positivamente el manejo de los pacientes en riesgo, tras colocarse el stent coronario\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ESPACIOS NO DESEADOS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Explic\u00f3 que la innovaci\u00f3n consiste en utilizar una gu\u00eda de angioplastia coronaria, y angular su extremo distal a 90 grados, para tratar de cruzar la Re-Estenosis Intra Stent, (crecimiento neointimal).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Indic\u00f3 que \u201cesto sin que la esta penetre hacia espacios no deseados (struts u celdas del stent), evitando con esto disecci\u00f3n de la arteria o mala colocaci\u00f3n del nuevo bal\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.-&nbsp;El cardi\u00f3logo dominicano Licurgo Cruz cre\u00f3 una nueva t\u00e9cnica que evita complicaciones tras la colocaci\u00f3n de un stent coronario, utilizado para&nbsp;asegurar un&nbsp;flujo&nbsp;sangu\u00edneo adecuado. El stent previene problemas cardiovasculares, como infarto al miocardio o angina de pecho. Estas dolencias est\u00e1n entre las principales causas de muerte en Rep\u00fablica Dominicana. Datos recientes reportan por esa causa unos 30 mil fallecimientos anuales, (35 por ciento de los ocurridos en el pa\u00eds). La aplicaci\u00f3n de la t\u00e9cnica del doctor Cruz se utiliza cuando ocurre la&nbsp;&nbsp;Re Estenosis Intra Stent (RIS), dificultad generada por el crecimiento de tejido dentro del stent, lo cual limita de nuevo el flujo sangu\u00edneo. LA \u00a8JACOBS TECHNIQUE\u00a8 Ante ese evento derivado de la colocaci\u00f3n del stent coronario, los pacientes podr\u00edan padecer s\u00edntomas como dolor en el pecho, dificultad para respirar e incluso nuevos ataques card\u00edacos. Cruz, cardi\u00f3logo hemodinamista que ofrece servicios especializados en el Hospital Metropolitano de Santiago (HOMS), es gobernador del Cap\u00edtulo Dominicano del Colegio Americano de Cardiolog\u00eda (ACC). Seg\u00fan explic\u00f3, la t\u00e9cnica nombrada \u201cJacobs Technique\u201d se utiliza dentro de un procedimiento y se puede estandarizar a nivel nacional y global. \u201cEsta t\u00e9cnica, asegur\u00f3, facilitar\u00e1 el tratamiento de la RIS e impactar\u00e1 positivamente el manejo de los pacientes en riesgo, tras colocarse el stent coronario\u201d. ESPACIOS NO DESEADOS Explic\u00f3 que la innovaci\u00f3n consiste en utilizar una gu\u00eda de angioplastia coronaria, y angular su extremo distal a 90 grados, para tratar de cruzar la Re-Estenosis Intra Stent, (crecimiento neointimal). Indic\u00f3 que \u201cesto sin que la esta penetre hacia espacios no deseados (struts u celdas del stent), evitando con esto disecci\u00f3n de la arteria o mala colocaci\u00f3n del nuevo bal\u00f3n.<\/p>\n","protected":false},"author":9,"featured_media":98922,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-98921","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/98921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=98921"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/98921\/revisions"}],"predecessor-version":[{"id":98923,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/98921\/revisions\/98923"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/98922"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=98921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=98921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=98921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}