{"id":99038,"date":"2024-09-07T07:33:44","date_gmt":"2024-09-07T11:33:44","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=99038"},"modified":"2024-09-07T07:34:15","modified_gmt":"2024-09-07T11:34:15","slug":"ee-uu-anuncia-apoyo-para-la-industrializacion-de-republica-dominicana","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ee-uu-anuncia-apoyo-para-la-industrializacion-de-republica-dominicana\/","title":{"rendered":"EE.UU anuncia apoyo para la industrializaci\u00f3n de Rep\u00fablica Dominicana"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"275\" height=\"183\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/09\/descarga-2.jpg\" alt=\"\" class=\"wp-image-99039\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El secretario de Estado de Estados Unidos, Antony Blinken, resalt\u00f3 ayer, durante su visita al presidente Luis Abinader en el PalacioNacional, que la Rep\u00fablica Dominicana ya es la econom\u00eda m\u00e1s grande del Caribe y una de las que est\u00e1n creciendo m\u00e1s r\u00e1pido en Latinoam\u00e9rica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Blinken record\u00f3 el acuerdo de cielos abiertos firmado el mes pasado entre ambas naciones, que permitir\u00e1 m\u00e1s vuelos comerciales entre ambos pa\u00edses y generar\u00e1 m\u00e1s comercio, turismo y empleos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anunci\u00f3 el lanzamiento de una nueva iniciativa entre tres universidades dominicanas y estadounidenses para dar a los estudiantes dominicanos capacidades en la industria de los semiconductores y la primera fase de una inversi\u00f3n de la cadena de suministro de la Usaid, con 3 millones de d\u00f3lares que ayudar\u00e1n al Gobierno dominicano para mejorar la capacitaci\u00f3n laboral, construir parques industriales y atraer a las industrias de alta tecnolog\u00eda en el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Consider\u00f3 que este programa adelantar\u00e1 las prioridades de la alianza para la prosperidad econ\u00f3mica de las Am\u00e9ricas, que incluye a una decena de pa\u00edses para modernizar las relaciones econ\u00f3micas, mejorar la protecci\u00f3n al trabajador y hacer m\u00e1s resilientes las cadenas de suministros. Destac\u00f3 el liderazgo de la Rep\u00fablica Dominicana en este esfuerzo, especialmente la transparencia y el estado de derecho que comparten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El secretario de Estado de Estados Unidos, Antony Blinken, cerr\u00f3 este viernes en Rep\u00fablica Dominicana una gira que le llev\u00f3 a Hait\u00ed y que enfoc\u00f3 en conseguir apoyos internacionales para que el depauperado pa\u00eds pueda celebrar elecciones en 2025 y poner freno a la violencia de las bandas armadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Blinken pas\u00f3 revista el jueves en Puerto Pr\u00edncipe al contingente de 380 polic\u00edas kenianos desplegados como parte de la Misi\u00f3n Multinacional de Apoyo a la Seguridad (MSS) y que avanza lentamente hacia los n\u00fameros de efectivos esperados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ayer, en Santo Domingo, Blinken y Abinader aseguraron que trabajar\u00e1n para pedir durante la Asamblea General de Naciones Unidas de este mes la renovaci\u00f3n del mandato para la MSS, que expira en octubre, y obtener nuevos compromisos de personal, que por el momento se limita al contingente keniano.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">LAS PREOCUPACIONES<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa situaci\u00f3n en Hait\u00ed es una preocupaci\u00f3n para sus vecinos y para todo el hemisferio. Agradezco al presidente (Abinader) por su rol vital de movilizar a la comunidad internacional. Lo que pasa en Hait\u00ed se nota mucho m\u00e1s all\u00e1 de Hait\u00ed\u201d, dijo Blinken.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHay una voluntad colectiva mayor para hacer algo efectivo sobre Hait\u00ed. Creo que hemos conseguido progresos reales, sin minimizar los desaf\u00edos que tenemos por delante\u201d, a\u00f1adi\u00f3 el jefe de la diplomacia estadounidense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los miembros de la misi\u00f3n, el coronel de la Polic\u00eda keniana Wafula Hesbon, asegur\u00f3 ayer a EFE que desde junio ha habido mejoras en su labor, como los m\u00e1s de 30 nuevos veh\u00edculos blindados antiminas MRAP que recientemente Estados Unidos envi\u00f3 a la base en el aeropuerto de Puerto Pr\u00edncipe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por el contrario, las marcas de los balazos eran evidentes en los maltrechos veh\u00edculos de la Polic\u00eda Nacional de Hait\u00ed, que adolece de falta de recursos, bajos salarios y corrupci\u00f3n, y que ahora opera bajo la declaraci\u00f3n del estado de emergencia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">REPERCUSIONES DE LA CRISIS HAITIANA<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Blinken record\u00f3 que la crisis haitiana, que a comienzos de a\u00f1o llev\u00f3 al pa\u00eds m\u00e1s pobre del Hemisferio Occidental a quedar en manos de bandas armadas, tiene repercusiones en todo el continente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNuestros futuros est\u00e1n unidos; el de Hait\u00ed, el de la Rep\u00fablica Dominicana y Estados Unidos\u201d, insisti\u00f3 el alto funcionario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Abinader afirm\u00f3 que se han dado pasos hacia la normalizaci\u00f3n de relaciones con Hait\u00ed y record\u00f3 que el desgobierno en ese pa\u00eds tiene efectos reales en \u201cpresi\u00f3n migratoria\u201d y en el sistema de salud dominicano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNuestra intenci\u00f3n es tratar de normalizar, en la medida de lo posible, las relaciones, pero siempre respetando y cuidando la seguridad de la Rep\u00fablica Dominicana\u201d, apunt\u00f3 el mandatario.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">LA CRISIS EN VENEZUELA<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto a la crisis pol\u00edtica en Venezuela, Biden y Abinader reiteraron que trabajar\u00e1n coordinadamente para pedir, con otros pa\u00edses latinoamericanos, el respeto a la democracia y al resultado de los comicios del 28 de julio, en los que el Consejo Nacional Electoral (CNE) dio como ganador a Nicol\u00e1s Maduro frente al opositor Edmundo Gonz\u00e1lez Urrutia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tanto Blinken como Abinader esquivaron las preguntas sobre el avi\u00f3n presidencial de Maduro confiscado por Estados Unidos en Rep\u00fabli<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El secretario de Estado de Estados Unidos, Antony Blinken, resalt\u00f3 ayer, durante su visita al presidente Luis Abinader en el PalacioNacional, que la Rep\u00fablica Dominicana ya es la econom\u00eda m\u00e1s grande del Caribe y una de las que est\u00e1n creciendo m\u00e1s r\u00e1pido en Latinoam\u00e9rica. Blinken record\u00f3 el acuerdo de cielos abiertos firmado el mes pasado entre ambas naciones, que permitir\u00e1 m\u00e1s vuelos comerciales entre ambos pa\u00edses y generar\u00e1 m\u00e1s comercio, turismo y empleos. Anunci\u00f3 el lanzamiento de una nueva iniciativa entre tres universidades dominicanas y estadounidenses para dar a los estudiantes dominicanos capacidades en la industria de los semiconductores y la primera fase de una inversi\u00f3n de la cadena de suministro de la Usaid, con 3 millones de d\u00f3lares que ayudar\u00e1n al Gobierno dominicano para mejorar la capacitaci\u00f3n laboral, construir parques industriales y atraer a las industrias de alta tecnolog\u00eda en el pa\u00eds. Consider\u00f3 que este programa adelantar\u00e1 las prioridades de la alianza para la prosperidad econ\u00f3mica de las Am\u00e9ricas, que incluye a una decena de pa\u00edses para modernizar las relaciones econ\u00f3micas, mejorar la protecci\u00f3n al trabajador y hacer m\u00e1s resilientes las cadenas de suministros. Destac\u00f3 el liderazgo de la Rep\u00fablica Dominicana en este esfuerzo, especialmente la transparencia y el estado de derecho que comparten. El secretario de Estado de Estados Unidos, Antony Blinken, cerr\u00f3 este viernes en Rep\u00fablica Dominicana una gira que le llev\u00f3 a Hait\u00ed y que enfoc\u00f3 en conseguir apoyos internacionales para que el depauperado pa\u00eds pueda celebrar elecciones en 2025 y poner freno a la violencia de las bandas armadas. Blinken pas\u00f3 revista el jueves en Puerto Pr\u00edncipe al contingente de 380 polic\u00edas kenianos desplegados como parte de la Misi\u00f3n Multinacional de Apoyo a la Seguridad (MSS) y que avanza lentamente hacia los n\u00fameros de efectivos esperados. Ayer, en Santo Domingo, Blinken y Abinader aseguraron que trabajar\u00e1n para pedir durante la Asamblea General de Naciones Unidas de este mes la renovaci\u00f3n del mandato para la MSS, que expira en octubre, y obtener nuevos compromisos de personal, que por el momento se limita al contingente keniano. LAS PREOCUPACIONES \u201cLa situaci\u00f3n en Hait\u00ed es una preocupaci\u00f3n para sus vecinos y para todo el hemisferio. Agradezco al presidente (Abinader) por su rol vital de movilizar a la comunidad internacional. Lo que pasa en Hait\u00ed se nota mucho m\u00e1s all\u00e1 de Hait\u00ed\u201d, dijo Blinken. \u201cHay una voluntad colectiva mayor para hacer algo efectivo sobre Hait\u00ed. Creo que hemos conseguido progresos reales, sin minimizar los desaf\u00edos que tenemos por delante\u201d, a\u00f1adi\u00f3 el jefe de la diplomacia estadounidense. Uno de los miembros de la misi\u00f3n, el coronel de la Polic\u00eda keniana Wafula Hesbon, asegur\u00f3 ayer a EFE que desde junio ha habido mejoras en su labor, como los m\u00e1s de 30 nuevos veh\u00edculos blindados antiminas MRAP que recientemente Estados Unidos envi\u00f3 a la base en el aeropuerto de Puerto Pr\u00edncipe. Por el contrario, las marcas de los balazos eran evidentes en los maltrechos veh\u00edculos de la Polic\u00eda Nacional de Hait\u00ed, que adolece de falta de recursos, bajos salarios y corrupci\u00f3n, y que ahora opera bajo la declaraci\u00f3n del estado de emergencia. REPERCUSIONES DE LA CRISIS HAITIANA Blinken record\u00f3 que la crisis haitiana, que a comienzos de a\u00f1o llev\u00f3 al pa\u00eds m\u00e1s pobre del Hemisferio Occidental a quedar en manos de bandas armadas, tiene repercusiones en todo el continente. \u201cNuestros futuros est\u00e1n unidos; el de Hait\u00ed, el de la Rep\u00fablica Dominicana y Estados Unidos\u201d, insisti\u00f3 el alto funcionario. Por su parte, Abinader afirm\u00f3 que se han dado pasos hacia la normalizaci\u00f3n de relaciones con Hait\u00ed y record\u00f3 que el desgobierno en ese pa\u00eds tiene efectos reales en \u201cpresi\u00f3n migratoria\u201d y en el sistema de salud dominicano. \u201cNuestra intenci\u00f3n es tratar de normalizar, en la medida de lo posible, las relaciones, pero siempre respetando y cuidando la seguridad de la Rep\u00fablica Dominicana\u201d, apunt\u00f3 el mandatario. LA CRISIS EN VENEZUELA En cuanto a la crisis pol\u00edtica en Venezuela, Biden y Abinader reiteraron que trabajar\u00e1n coordinadamente para pedir, con otros pa\u00edses latinoamericanos, el respeto a la democracia y al resultado de los comicios del 28 de julio, en los que el Consejo Nacional Electoral (CNE) dio como ganador a Nicol\u00e1s Maduro frente al opositor Edmundo Gonz\u00e1lez Urrutia. Tanto Blinken como Abinader esquivaron las preguntas sobre el avi\u00f3n presidencial de Maduro confiscado por Estados Unidos en Rep\u00fabli<\/p>\n","protected":false},"author":9,"featured_media":99039,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-99038","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/99038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=99038"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/99038\/revisions"}],"predecessor-version":[{"id":99040,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/99038\/revisions\/99040"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/99039"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=99038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=99038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=99038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}