{"id":99316,"date":"2024-09-22T08:07:07","date_gmt":"2024-09-22T12:07:07","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=99316"},"modified":"2024-09-22T08:07:09","modified_gmt":"2024-09-22T12:07:09","slug":"alertan-en-la-rd-una-atencion-rapida-para-sobrevivir-a-infarto","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/alertan-en-la-rd-una-atencion-rapida-para-sobrevivir-a-infarto\/","title":{"rendered":"Alertan en la RD una atenci\u00f3n r\u00e1pida para sobrevivir a infarto"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"165\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/09\/Sintomas-infarto3-1-300x165-1.jpg\" alt=\"\" class=\"wp-image-99317\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong> REP\u00daBLICA DOMINICANA.-<\/strong>\u00a0El tiempo entre el diagn\u00f3stico de infarto y la atenci\u00f3n m\u00e9dica contin\u00faa como el tal\u00f3n de Aquiles para salvar la vida, afirmaron expertos en este balneario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed coincidieron el ministro de Salud dominicano, Dr. V\u00edctor Atallah y otros especialistas asistentes al Congreso Latinoamericano del Colegio Americano de Cardiolog\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los m\u00e9dicos estimaron en sus intervenciones que los infartos son causa principal de muerte en enfermedades cardiovasculares (ECV) e insisten en una atenci\u00f3n oportuna e intervenci\u00f3n a tiempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>RED DE SALUD<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al disertar en el evento que se desarrolla en esa zona tur\u00edstica,&nbsp;&nbsp;Atallah asegur\u00f3 que la Red Nacional de Salud de Dominicana resolver\u00e1 parte de esa situaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cVamos a reducir a menos de dos horas el tiempo, dijo, desde que se produce el s\u00edntoma, hasta recibir el tratamiento\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Admiti\u00f3 que el tema sigue siendo el tal\u00f3n de Aquiles en las muertes por infartos al miocardio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SISTEMA DE EMERGENCIAS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ministro observ\u00f3 la organizaci\u00f3n de los hospitales y el Sistema de Emergencias 911 para que, mediante una aplicaci\u00f3n, el paciente sea recibido y atendido de inmediato en el centro de salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El doctor Licurgo Cruz, gobernador del Cap\u00edtulo Dominicano del Colegio Americano de Cardiolog\u00eda, afirm\u00f3 que todav\u00eda hay causas que hacen lento el cuidado de los infartados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mencion\u00f3 entre ellas la idiosincrasia del paciente con automedicaci\u00f3n y la b\u00fasqueda de ayuda m\u00e9dica de forma tard\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SISTEMA 911<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Valor\u00f3 el rol del Sistema 911 en mejorar la situaci\u00f3n, adem\u00e1s de que hay suficientes medicamentos vitales disponibles para preservar la vida en muchos centros de salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cruz inform\u00f3 que la agenda cient\u00edfica incluye 118 conferencias, simposios y sesiones tem\u00e1ticos, plenarias, y presentaci\u00f3n de casos cl\u00ednicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el evento participan 107 expositores y 660 cardi\u00f3logos del pa\u00eds, Estados Unidos y Latinoam\u00e9rica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REP\u00daBLICA DOMINICANA.-\u00a0El tiempo entre el diagn\u00f3stico de infarto y la atenci\u00f3n m\u00e9dica contin\u00faa como el tal\u00f3n de Aquiles para salvar la vida, afirmaron expertos en este balneario. As\u00ed coincidieron el ministro de Salud dominicano, Dr. V\u00edctor Atallah y otros especialistas asistentes al Congreso Latinoamericano del Colegio Americano de Cardiolog\u00eda. Los m\u00e9dicos estimaron en sus intervenciones que los infartos son causa principal de muerte en enfermedades cardiovasculares (ECV) e insisten en una atenci\u00f3n oportuna e intervenci\u00f3n a tiempo. RED DE SALUD Al disertar en el evento que se desarrolla en esa zona tur\u00edstica,&nbsp;&nbsp;Atallah asegur\u00f3 que la Red Nacional de Salud de Dominicana resolver\u00e1 parte de esa situaci\u00f3n. \u201cVamos a reducir a menos de dos horas el tiempo, dijo, desde que se produce el s\u00edntoma, hasta recibir el tratamiento\u201d. Admiti\u00f3 que el tema sigue siendo el tal\u00f3n de Aquiles en las muertes por infartos al miocardio. SISTEMA DE EMERGENCIAS El ministro observ\u00f3 la organizaci\u00f3n de los hospitales y el Sistema de Emergencias 911 para que, mediante una aplicaci\u00f3n, el paciente sea recibido y atendido de inmediato en el centro de salud. El doctor Licurgo Cruz, gobernador del Cap\u00edtulo Dominicano del Colegio Americano de Cardiolog\u00eda, afirm\u00f3 que todav\u00eda hay causas que hacen lento el cuidado de los infartados. Mencion\u00f3 entre ellas la idiosincrasia del paciente con automedicaci\u00f3n y la b\u00fasqueda de ayuda m\u00e9dica de forma tard\u00eda. SISTEMA 911 Valor\u00f3 el rol del Sistema 911 en mejorar la situaci\u00f3n, adem\u00e1s de que hay suficientes medicamentos vitales disponibles para preservar la vida en muchos centros de salud. Cruz inform\u00f3 que la agenda cient\u00edfica incluye 118 conferencias, simposios y sesiones tem\u00e1ticos, plenarias, y presentaci\u00f3n de casos cl\u00ednicos. En el evento participan 107 expositores y 660 cardi\u00f3logos del pa\u00eds, Estados Unidos y Latinoam\u00e9rica.<\/p>\n","protected":false},"author":9,"featured_media":99317,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-99316","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/99316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=99316"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/99316\/revisions"}],"predecessor-version":[{"id":99318,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/99316\/revisions\/99318"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/99317"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=99316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=99316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=99316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}