{"id":99615,"date":"2024-10-10T06:50:18","date_gmt":"2024-10-10T10:50:18","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=99615"},"modified":"2024-10-10T06:50:22","modified_gmt":"2024-10-10T10:50:22","slug":"milton-baja-a-categoria-2-tras-llegar-a-florida-y-causa-inundaciones-repentinas-en-tampa","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/milton-baja-a-categoria-2-tras-llegar-a-florida-y-causa-inundaciones-repentinas-en-tampa\/","title":{"rendered":"Milton baja a categor\u00eda 2 tras llegar a Florida y causa inundaciones repentinas en Tampa"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"223\" height=\"163\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/10\/tor.jpg\" alt=\"\" class=\"wp-image-99616\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Miami.-<\/strong>&nbsp;El hurac\u00e1n Milton perdi\u00f3 este mi\u00e9rcoles potencia y baj\u00f3 a categor\u00eda 2, con vientos m\u00e1ximos sostenidos de 175 kil\u00f3metros por hora (110 millas), tras tocar tierra en Siesta Key, en la costa oeste de Florida, pero a\u00fan representa un peligro importante por las r\u00e1fagas de viento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Centro Nacional de Huracanes (NHC, en ingl\u00e9s) detall\u00f3 en su \u00faltimo bolet\u00edn que Milton adem\u00e1s est\u00e1 provocando inundaciones repentinas en el \u00e1rea de la Bah\u00eda de Tampa mientras avanza hacia el este de Florida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Milton toc\u00f3 tierra la noche de este mi\u00e9rcoles en Siesta Key, cerca de la ciudad de Sarasota, sobre las 8:30 de la noche, hora local del este (00:30 GMT) como un hurac\u00e1n categor\u00eda 3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan el NHC, el fen\u00f3meno ha perdido fuerza pero a\u00fan se reportan r\u00e1fagas de hasta 164 kil\u00f3metros por hora (101 millas).&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miami.-&nbsp;El hurac\u00e1n Milton perdi\u00f3 este mi\u00e9rcoles potencia y baj\u00f3 a categor\u00eda 2, con vientos m\u00e1ximos sostenidos de 175 kil\u00f3metros por hora (110 millas), tras tocar tierra en Siesta Key, en la costa oeste de Florida, pero a\u00fan representa un peligro importante por las r\u00e1fagas de viento. El Centro Nacional de Huracanes (NHC, en ingl\u00e9s) detall\u00f3 en su \u00faltimo bolet\u00edn que Milton adem\u00e1s est\u00e1 provocando inundaciones repentinas en el \u00e1rea de la Bah\u00eda de Tampa mientras avanza hacia el este de Florida. Milton toc\u00f3 tierra la noche de este mi\u00e9rcoles en Siesta Key, cerca de la ciudad de Sarasota, sobre las 8:30 de la noche, hora local del este (00:30 GMT) como un hurac\u00e1n categor\u00eda 3. Seg\u00fan el NHC, el fen\u00f3meno ha perdido fuerza pero a\u00fan se reportan r\u00e1fagas de hasta 164 kil\u00f3metros por hora (101 millas).&nbsp;<\/p>\n","protected":false},"author":9,"featured_media":99616,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-99615","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/99615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=99615"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/99615\/revisions"}],"predecessor-version":[{"id":99617,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/99615\/revisions\/99617"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/99616"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=99615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=99615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=99615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}