{"id":99633,"date":"2024-10-19T11:13:17","date_gmt":"2024-10-19T15:13:17","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=99633"},"modified":"2024-10-19T11:13:17","modified_gmt":"2024-10-19T15:13:17","slug":"curso-taller-derecho-municipal-impartido-en-sosua-para-jefes-de-departamentos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/curso-taller-derecho-municipal-impartido-en-sosua-para-jefes-de-departamentos\/","title":{"rendered":"Curso-taller Derecho municipal impartido en Sos\u00faa para Jefes de Departamentos"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/10\/taller-derecho-municipal-1024x768.jpg\" alt=\"\" class=\"wp-image-99634\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/10\/taller-derecho-municipal-1024x768.jpg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/10\/taller-derecho-municipal-300x225.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/10\/taller-derecho-municipal-768x576.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/10\/taller-derecho-municipal-600x450.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/10\/taller-derecho-municipal.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\">El Batey, Sos\u00faa.- El alcalde Wilfredo Olivences, comprometido con el fortalecimiento del gobierno municipal, encabez\u00f3 el curso-taller denominado \u2018Derecho Municipal\u2019, que ser\u00e1 impartido por el magistrado Nassin Eduardo Ovalle Est\u00e9vez. <\/h5>\n\n\n\n<h5 class=\"wp-block-heading\">El curso, que se desarrolla durante ocho viernes consecutivos, est\u00e1 destinado a todos los jefes de departamento del gobierno municipal. En la inauguraci\u00f3n del curso estuvieron presentes no solo el alcalde Olivences, sino tambi\u00e9n todos los concejales y miembros del equipo jur\u00eddico, entre ellos los se\u00f1ores Jos\u00e9 Ram\u00f3n Valbuena Valdez y Johanna Ramos.<\/h5>\n\n\n\n<h5 class=\"wp-block-heading\">Este taller tiene como objetivo brindar una formaci\u00f3n integral en los \u00e1mbitos jur\u00eddicos y administrativos del derecho municipal, con el objetivo de mejorar la eficacia y transparencia de la gesti\u00f3n p\u00fablica. <\/h5>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/10\/taller-derecho-municipal2-1024x768.jpg\" alt=\"\" class=\"wp-image-99635\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/10\/taller-derecho-municipal2-1024x768.jpg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/10\/taller-derecho-municipal2-300x225.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/10\/taller-derecho-municipal2-768x576.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/10\/taller-derecho-municipal2-600x450.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/10\/taller-derecho-municipal2.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\">El curso es una iniciativa importante para seguir impulsando la profesionalizaci\u00f3n y el fortalecimiento institucional de la administraci\u00f3n municipal, garantizando que los titulares de los departamentos cuenten con las herramientas necesarias para la correcta aplicaci\u00f3n de la normatividad y la mejora continua de los servicios municipales.<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>El Batey, Sos\u00faa.- El alcalde Wilfredo Olivences, comprometido con el fortalecimiento del gobierno municipal, encabez\u00f3 el curso-taller denominado \u2018Derecho Municipal\u2019, que ser\u00e1 impartido por el magistrado Nassin Eduardo Ovalle Est\u00e9vez. El curso, que se desarrolla durante ocho viernes consecutivos, est\u00e1 destinado a todos los jefes de departamento del gobierno municipal. En la inauguraci\u00f3n del curso estuvieron presentes no solo el alcalde Olivences, sino tambi\u00e9n todos los concejales y miembros del equipo jur\u00eddico, entre ellos los se\u00f1ores Jos\u00e9 Ram\u00f3n Valbuena Valdez y Johanna Ramos. Este taller tiene como objetivo brindar una formaci\u00f3n integral en los \u00e1mbitos jur\u00eddicos y administrativos del derecho municipal, con el objetivo de mejorar la eficacia y transparencia de la gesti\u00f3n p\u00fablica. El curso es una iniciativa importante para seguir impulsando la profesionalizaci\u00f3n y el fortalecimiento institucional de la administraci\u00f3n municipal, garantizando que los titulares de los departamentos cuenten con las herramientas necesarias para la correcta aplicaci\u00f3n de la normatividad y la mejora continua de los servicios municipales.<\/p>\n","protected":false},"author":12,"featured_media":99634,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-99633","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sosua-en-el-mundo"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/99633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=99633"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/99633\/revisions"}],"predecessor-version":[{"id":99759,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/99633\/revisions\/99759"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/99634"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=99633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=99633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=99633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}