{"id":99668,"date":"2024-10-14T07:56:17","date_gmt":"2024-10-14T11:56:17","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=99668"},"modified":"2024-10-14T07:56:20","modified_gmt":"2024-10-14T11:56:20","slug":"guillermo-gomez-denuncia-presiones-del-ministerio-publico-en-el-caso-camaleon","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/guillermo-gomez-denuncia-presiones-del-ministerio-publico-en-el-caso-camaleon\/","title":{"rendered":"Guillermo G\u00f3mez denuncia presiones del Ministerio P\u00fablico en el caso Camale\u00f3n"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/10\/64662a2abb792.jpeg\" alt=\"\" class=\"wp-image-99669\" width=\"214\" height=\"166\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/10\/64662a2abb792.jpeg 800w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/10\/64662a2abb792-300x233.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/10\/64662a2abb792-768x597.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/10\/64662a2abb792-600x467.jpeg 600w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SANTO DOMINGO. \u2013 Guillermo G\u00f3mez, el periodista y padre de Jos\u00e9 \u00c1ngel G\u00f3mez Cana\u00e1n (Jochi G\u00f3mez),&nbsp;<\/strong>propietario de&nbsp;<strong>Transcore Latam y Aurix,<\/strong>&nbsp;realiz\u00f3 varias acusaciones contra el Ministerio P\u00fablico (MP), al denunciar que su hijo fue presionado para acusar al exdirector del Instituto Nacional de Tr\u00e1nsito y Transporte Terrestre (Intrant), Hugo Beras, de recibir sobornos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">G\u00f3mez, durante su programa de televisi\u00f3n \u201cAeromundo\u201d, dijo que las autoridades le ofrecieron a su hijo reducir las consecuencias legales si acced\u00eda a incriminar a Beras. \u201cNosotros no acusamos a nadie y menos a Hugo Beras para salvar a mi hijo, como han hecho con otros. Si lo acusaba, ya ten\u00edan el caso armado contra \u00e9l,\u201d expres\u00f3. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Acusaciones de manipulaci\u00f3n judicial en la audiencia<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En la misma intervenci\u00f3n, G\u00f3mez lanz\u00f3 una acusaci\u00f3n grave sobre presiones judiciales. Asegur\u00f3 que, durante los debates de la audiencia de medida de coerci\u00f3n, tres jueces penales ingresaron a la sala con un documento que conten\u00eda sus nombres, lo que, seg\u00fan \u00e9l, fue un intento de influir en la jueza que inicialmente no pretend\u00eda imponer prisi\u00f3n preventiva para los imputados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cYo voy a defender a mi hijo hasta las \u00faltimas consecuencias,\u201d declar\u00f3 G\u00f3mez al concluir su programa, insistiendo en que todo esto forma parte de una campa\u00f1a de desprestigio orquestada desde el Ministerio P\u00fablico mediante filtraciones a los medios de comunicaci\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El caso Camale\u00f3n y los cargos contra los involucrados<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Jos\u00e9 \u00c1ngel G\u00f3mez Cana\u00e1n, conocido como Jochi G\u00f3mez, enfrenta serias acusaciones, entre las que se encuentran asociaci\u00f3n de malhechores, estafa contra el Estado, desfalco, lavado de activos, y usurpaci\u00f3n de identidades empresariales. Seg\u00fan el Ministerio P\u00fablico, su empresa Transcore Latam jug\u00f3 un papel central en el esquema fraudulento, al desviar fondos p\u00fablicos mediante la manipulaci\u00f3n del proyecto de modernizaci\u00f3n de la red semaf\u00f3rica del Gran Santo Domingo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, las autoridades se\u00f1alan que Hugo Beras, durante su gesti\u00f3n en el Intrant, facilit\u00f3 la integraci\u00f3n de nuevas autoridades que colaboraron en el esquema. El Ministerio P\u00fablico sostiene que Beras permiti\u00f3 la participaci\u00f3n de empresas de carpeta, utilizadas para desviar recursos del Estado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Medidas de coerci\u00f3n: Prisi\u00f3n preventiva para Beras y Padovani<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El Juzgado de Atenci\u00f3n Permanente del Distrito Nacional impuso 18 meses de prisi\u00f3n preventiva en la c\u00e1rcel de Najayo para Hugo Beras y Pedro Vinicio Padovani B\u00e1ez, exencargado del Centro de Control de Tr\u00e1fico del Intrant. Ambos enfrentan cargos relacionados con su participaci\u00f3n en el esquema de corrupci\u00f3n que ha salido a la luz como el Caso Camale\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para otros imputados, como Frank D\u00edaz Warden, representante de Beras ante el Comit\u00e9 de Compras del Intrant, y Carlos Jos\u00e9 Peguero Vargas, el tribunal dict\u00f3 medidas cautelares que incluyen garant\u00eda econ\u00f3mica, impedimento de salida del pa\u00eds y presentaci\u00f3n peri\u00f3dica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO. \u2013 Guillermo G\u00f3mez, el periodista y padre de Jos\u00e9 \u00c1ngel G\u00f3mez Cana\u00e1n (Jochi G\u00f3mez),&nbsp;propietario de&nbsp;Transcore Latam y Aurix,&nbsp;realiz\u00f3 varias acusaciones contra el Ministerio P\u00fablico (MP), al denunciar que su hijo fue presionado para acusar al exdirector del Instituto Nacional de Tr\u00e1nsito y Transporte Terrestre (Intrant), Hugo Beras, de recibir sobornos. G\u00f3mez, durante su programa de televisi\u00f3n \u201cAeromundo\u201d, dijo que las autoridades le ofrecieron a su hijo reducir las consecuencias legales si acced\u00eda a incriminar a Beras. \u201cNosotros no acusamos a nadie y menos a Hugo Beras para salvar a mi hijo, como han hecho con otros. Si lo acusaba, ya ten\u00edan el caso armado contra \u00e9l,\u201d expres\u00f3. Acusaciones de manipulaci\u00f3n judicial en la audiencia En la misma intervenci\u00f3n, G\u00f3mez lanz\u00f3 una acusaci\u00f3n grave sobre presiones judiciales. Asegur\u00f3 que, durante los debates de la audiencia de medida de coerci\u00f3n, tres jueces penales ingresaron a la sala con un documento que conten\u00eda sus nombres, lo que, seg\u00fan \u00e9l, fue un intento de influir en la jueza que inicialmente no pretend\u00eda imponer prisi\u00f3n preventiva para los imputados. \u201cYo voy a defender a mi hijo hasta las \u00faltimas consecuencias,\u201d declar\u00f3 G\u00f3mez al concluir su programa, insistiendo en que todo esto forma parte de una campa\u00f1a de desprestigio orquestada desde el Ministerio P\u00fablico mediante filtraciones a los medios de comunicaci\u00f3n. El caso Camale\u00f3n y los cargos contra los involucrados Jos\u00e9 \u00c1ngel G\u00f3mez Cana\u00e1n, conocido como Jochi G\u00f3mez, enfrenta serias acusaciones, entre las que se encuentran asociaci\u00f3n de malhechores, estafa contra el Estado, desfalco, lavado de activos, y usurpaci\u00f3n de identidades empresariales. Seg\u00fan el Ministerio P\u00fablico, su empresa Transcore Latam jug\u00f3 un papel central en el esquema fraudulento, al desviar fondos p\u00fablicos mediante la manipulaci\u00f3n del proyecto de modernizaci\u00f3n de la red semaf\u00f3rica del Gran Santo Domingo. Por otro lado, las autoridades se\u00f1alan que Hugo Beras, durante su gesti\u00f3n en el Intrant, facilit\u00f3 la integraci\u00f3n de nuevas autoridades que colaboraron en el esquema. El Ministerio P\u00fablico sostiene que Beras permiti\u00f3 la participaci\u00f3n de empresas de carpeta, utilizadas para desviar recursos del Estado. Medidas de coerci\u00f3n: Prisi\u00f3n preventiva para Beras y Padovani El Juzgado de Atenci\u00f3n Permanente del Distrito Nacional impuso 18 meses de prisi\u00f3n preventiva en la c\u00e1rcel de Najayo para Hugo Beras y Pedro Vinicio Padovani B\u00e1ez, exencargado del Centro de Control de Tr\u00e1fico del Intrant. Ambos enfrentan cargos relacionados con su participaci\u00f3n en el esquema de corrupci\u00f3n que ha salido a la luz como el Caso Camale\u00f3n. Para otros imputados, como Frank D\u00edaz Warden, representante de Beras ante el Comit\u00e9 de Compras del Intrant, y Carlos Jos\u00e9 Peguero Vargas, el tribunal dict\u00f3 medidas cautelares que incluyen garant\u00eda econ\u00f3mica, impedimento de salida del pa\u00eds y presentaci\u00f3n peri\u00f3dica.<\/p>\n","protected":false},"author":9,"featured_media":99669,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-99668","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/99668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=99668"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/99668\/revisions"}],"predecessor-version":[{"id":99670,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/99668\/revisions\/99670"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/99669"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=99668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=99668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=99668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}