{"id":99924,"date":"2024-10-29T07:10:44","date_gmt":"2024-10-29T11:10:44","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=99924"},"modified":"2024-10-29T07:10:46","modified_gmt":"2024-10-29T11:10:46","slug":"aguilas-derrotan-a-las-estrellas-y-ponen-fin-mala-racha-beisbol-rd","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/aguilas-derrotan-a-las-estrellas-y-ponen-fin-mala-racha-beisbol-rd\/","title":{"rendered":"Aguilas derrotan a las Estrellas y ponen fin mala racha beisbol RD"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/10\/pedro-300x200-1.jpeg\" alt=\"\" class=\"wp-image-99925\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">SANTIAGO .- Las \u00c1guilas Cibae\u00f1as estrenaron manager y victoria en el estadio Cibao, al imponerse a las Estrellas Orientales 6-4, en un partido celebrado anoche, en la continuaci\u00f3n del torneo de b\u00e9isbol profesional 2024\/2025, dedicado a don Jos\u00e9 Le\u00f3n Asensio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las \u00c1guilas trajeron al boricua Yadier Molina desde Puerto Rico y, de inmediato, se puso al frente del equipo, logrando acabar con una cadena de 2 blanqueadas que ten\u00eda el equipo y 4 derrotas corridas en su casa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La victoria se la anot\u00f3 Rodrigo Benoit (2-0), con derrota para Ram\u00f3n Santos (0-1) y juego salvado para Pedro Strop (2).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los due\u00f1os de casa iniciaron con el zurdo Braulio Torres, quien lanz\u00f3 2 cap\u00edtulos, permiti\u00f3 2 carreras, fue tocado con 6 hits, 2 transferencias y no ponch\u00f3 a ninguno de los 12 bateadores que enfrent\u00f3. Luego desfilaron por el mont\u00edculo amarillo Carlos Espinal (3), Rodrigo Benoit (4), Jahn Mari\u00f1ez (6), Richard Rodr\u00edguez (7), Luis Gonz\u00e1lez (8) y Pedro Strop (8).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El zurdo cubano Andy Otero comenz\u00f3 en el box de los visitantes, actuando en 2.2 episodios. Enfrent\u00f3 a 13 bateadores, acept\u00f3 4 imparables, 2 bases por bolas y abanic\u00f3 a uno. Despu\u00e9s escalaron la lomita Rom\u00e1n M\u00e9ndez (3), Ram\u00f3n Santos (4), Carlos G\u00f3mez (4), Jos\u00e9 Manuel Fern\u00e1ndez (4), Ger\u00f3nimo Franz\u00faa (5), Carlos Bel\u00e9n (6), Jefry Yan (7) y Jefrey Col\u00f3n (8).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Yairo Mu\u00f1oz dispar\u00f3 su segundo hit en el octavo episodio, siendo el n\u00famero 100 en su carrera en Lidom. Despu\u00e9s de los dos cohetazos de Mu\u00f1oz, los jugadores se distribuyeron los 8 imparables restantes entre Jonathan Villar, Starlin Castro, Erick Mej\u00eda, Jos\u00e9 Rodr\u00edguez, Eddys Leonard, Julio Rodr\u00edguez, Jefri P\u00e9rez y Jerar Encarnaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los verdes no se hicieron esperar y fabricaron dos anotaciones en la primera entrada. Vidal Brujan abri\u00f3 con hit al left, Euribel \u00c1ngeles lo imit\u00f3 por primera, Brujan fue eliminado en tercera en jugada de selecci\u00f3n. Raimel Tapia conect\u00f3 un sencillo por la intermedia y \u00c1ngeles anot\u00f3 la primera, mientras Tapia pis\u00f3 el plato con la segunda por balk.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La sequ\u00eda de las \u00c1guilas se acab\u00f3 en el tercer episodio, cuando marcaron 3 carreras enviando 8 bateadores al plato. El fest\u00edn comenz\u00f3 con sencillos consecutivos de Eddys Leonard y Julio Rodr\u00edguez. Bladimir Restituyo intent\u00f3 sacrificarse, pero Leonard fue cazado en tercera. Jonathan Villar fall\u00f3 con elevado al bosque derecho, Jerar Encarnaci\u00f3n negoci\u00f3 boleto, Starlin Castro igual\u00f3 el partido con metrallazo al centro y Erick Mej\u00eda impuls\u00f3 la tercera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero las \u00c1guilas volvieron a la carga en el cuarto con 3 carreras m\u00e1s. Yairo Mu\u00f1oz abri\u00f3 con metrallazo, rob\u00f3 segunda y avanz\u00f3 a tercera por error en tiro. Leonard negoci\u00f3 transferencia, Julio Rodr\u00edguez fue golpeado, Bladimir Restituyo se col\u00f3 en primera por jugada de selecci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Yairo fue puesto out, Jonathan Villar bate\u00f3 un cohetazo y anot\u00f3 Leonard, mientras Restituyo se fue a tercera. Encarnaci\u00f3n recibi\u00f3 transferencia y Castro remolc\u00f3 a Restituyo con elevado de sacrificio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTIAGO .- Las \u00c1guilas Cibae\u00f1as estrenaron manager y victoria en el estadio Cibao, al imponerse a las Estrellas Orientales 6-4, en un partido celebrado anoche, en la continuaci\u00f3n del torneo de b\u00e9isbol profesional 2024\/2025, dedicado a don Jos\u00e9 Le\u00f3n Asensio. Las \u00c1guilas trajeron al boricua Yadier Molina desde Puerto Rico y, de inmediato, se puso al frente del equipo, logrando acabar con una cadena de 2 blanqueadas que ten\u00eda el equipo y 4 derrotas corridas en su casa. La victoria se la anot\u00f3 Rodrigo Benoit (2-0), con derrota para Ram\u00f3n Santos (0-1) y juego salvado para Pedro Strop (2). Los due\u00f1os de casa iniciaron con el zurdo Braulio Torres, quien lanz\u00f3 2 cap\u00edtulos, permiti\u00f3 2 carreras, fue tocado con 6 hits, 2 transferencias y no ponch\u00f3 a ninguno de los 12 bateadores que enfrent\u00f3. Luego desfilaron por el mont\u00edculo amarillo Carlos Espinal (3), Rodrigo Benoit (4), Jahn Mari\u00f1ez (6), Richard Rodr\u00edguez (7), Luis Gonz\u00e1lez (8) y Pedro Strop (8). El zurdo cubano Andy Otero comenz\u00f3 en el box de los visitantes, actuando en 2.2 episodios. Enfrent\u00f3 a 13 bateadores, acept\u00f3 4 imparables, 2 bases por bolas y abanic\u00f3 a uno. Despu\u00e9s escalaron la lomita Rom\u00e1n M\u00e9ndez (3), Ram\u00f3n Santos (4), Carlos G\u00f3mez (4), Jos\u00e9 Manuel Fern\u00e1ndez (4), Ger\u00f3nimo Franz\u00faa (5), Carlos Bel\u00e9n (6), Jefry Yan (7) y Jefrey Col\u00f3n (8). Yairo Mu\u00f1oz dispar\u00f3 su segundo hit en el octavo episodio, siendo el n\u00famero 100 en su carrera en Lidom. Despu\u00e9s de los dos cohetazos de Mu\u00f1oz, los jugadores se distribuyeron los 8 imparables restantes entre Jonathan Villar, Starlin Castro, Erick Mej\u00eda, Jos\u00e9 Rodr\u00edguez, Eddys Leonard, Julio Rodr\u00edguez, Jefri P\u00e9rez y Jerar Encarnaci\u00f3n. Los verdes no se hicieron esperar y fabricaron dos anotaciones en la primera entrada. Vidal Brujan abri\u00f3 con hit al left, Euribel \u00c1ngeles lo imit\u00f3 por primera, Brujan fue eliminado en tercera en jugada de selecci\u00f3n. Raimel Tapia conect\u00f3 un sencillo por la intermedia y \u00c1ngeles anot\u00f3 la primera, mientras Tapia pis\u00f3 el plato con la segunda por balk. La sequ\u00eda de las \u00c1guilas se acab\u00f3 en el tercer episodio, cuando marcaron 3 carreras enviando 8 bateadores al plato. El fest\u00edn comenz\u00f3 con sencillos consecutivos de Eddys Leonard y Julio Rodr\u00edguez. Bladimir Restituyo intent\u00f3 sacrificarse, pero Leonard fue cazado en tercera. Jonathan Villar fall\u00f3 con elevado al bosque derecho, Jerar Encarnaci\u00f3n negoci\u00f3 boleto, Starlin Castro igual\u00f3 el partido con metrallazo al centro y Erick Mej\u00eda impuls\u00f3 la tercera. Pero las \u00c1guilas volvieron a la carga en el cuarto con 3 carreras m\u00e1s. Yairo Mu\u00f1oz abri\u00f3 con metrallazo, rob\u00f3 segunda y avanz\u00f3 a tercera por error en tiro. Leonard negoci\u00f3 transferencia, Julio Rodr\u00edguez fue golpeado, Bladimir Restituyo se col\u00f3 en primera por jugada de selecci\u00f3n. Yairo fue puesto out, Jonathan Villar bate\u00f3 un cohetazo y anot\u00f3 Leonard, mientras Restituyo se fue a tercera. Encarnaci\u00f3n recibi\u00f3 transferencia y Castro remolc\u00f3 a Restituyo con elevado de sacrificio.<\/p>\n","protected":false},"author":9,"featured_media":99925,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-99924","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/99924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=99924"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/99924\/revisions"}],"predecessor-version":[{"id":99926,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/99924\/revisions\/99926"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/99925"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=99924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=99924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=99924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}