{"id":99991,"date":"2024-11-02T17:23:32","date_gmt":"2024-11-02T21:23:32","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=99991"},"modified":"2024-11-02T17:23:33","modified_gmt":"2024-11-02T21:23:33","slug":"defensa-civil-cierra-las-playas-de-puerto-plata-por-fuerte-oleaje","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/defensa-civil-cierra-las-playas-de-puerto-plata-por-fuerte-oleaje\/","title":{"rendered":"Defensa Civil cierra las playas de Puerto Plata por fuerte oleaje"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/11\/Defensa-Civil-Puerto-Plata-1024x596.jpg\" alt=\"\" class=\"wp-image-99992\" width=\"293\" height=\"170\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/11\/Defensa-Civil-Puerto-Plata-1024x596.jpg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/11\/Defensa-Civil-Puerto-Plata-300x175.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/11\/Defensa-Civil-Puerto-Plata-768x447.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/11\/Defensa-Civil-Puerto-Plata-600x349.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2024\/11\/Defensa-Civil-Puerto-Plata.jpg 1115w\" sizes=\"auto, (max-width: 293px) 100vw, 293px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"> \u00a0Puerto Plata , 2 nov (EFE).- La Defensa Civil inform\u00f3 este s\u00e1bado del cierre de todas las playas de Puerto Plata, como medida preventiva, ante el fuerte oleaje y vientos en la zona, a causa de la vaguada que incide sobre el pa\u00eds y que mantiene a esa provincia y a otras ocho en alerta amarilla (intermedia).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de un comunicado, el director en la zona, Whascar Garc\u00eda, indic\u00f3 que en todas las playas se coloc\u00f3 bandera roja, adem\u00e1s se realizaron perifoneos preventivos en las comunidades m\u00e1s vulnerables, como parte de las medidas tomadas para preservar vidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s temprano, el Instituto Dominicano de Meteorolog\u00eda (Indomet) recomend\u00f3 a los operadores de fr\u00e1giles, peque\u00f1as y medianas embarcaciones en la costa atl\u00e1ntica, permanecer en puerto, debido a vientos anormales y olas de 7 a 9 pies cerca de la costa, siendo superiores, mar a dentro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A causa de las lluvias, provocadas por una vaguada, el presidente Luis Abinader se reunir\u00e1 este s\u00e1bado en la sede del Centro de Operaciones de Emergencias (COE) con representantes de los organismos de emergencia para dar seguimiento a la situaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El COE mantiene en alerta amarilla las provincias de Puerto Plata, Mar\u00eda Trinidad S\u00e1nchez, Espaillat, Hato Mayor, El Seibo, La Altagracia, Duarte, Saman\u00e1 y Hermanas Mirabal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras que en alerta verde est\u00e1n Santo Domingo, Distrito Nacional, La Vega, Montecristi y Santiago.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese sentido, se recomienda a las personas abstenerse de cruzar, r\u00edos, arroyos y ca\u00f1adas que presenten altos vol\u00famenes de agua en las provincias bajo alerta.EFE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Puerto Plata , 2 nov (EFE).- La Defensa Civil inform\u00f3 este s\u00e1bado del cierre de todas las playas de Puerto Plata, como medida preventiva, ante el fuerte oleaje y vientos en la zona, a causa de la vaguada que incide sobre el pa\u00eds y que mantiene a esa provincia y a otras ocho en alerta amarilla (intermedia). A trav\u00e9s de un comunicado, el director en la zona, Whascar Garc\u00eda, indic\u00f3 que en todas las playas se coloc\u00f3 bandera roja, adem\u00e1s se realizaron perifoneos preventivos en las comunidades m\u00e1s vulnerables, como parte de las medidas tomadas para preservar vidas. M\u00e1s temprano, el Instituto Dominicano de Meteorolog\u00eda (Indomet) recomend\u00f3 a los operadores de fr\u00e1giles, peque\u00f1as y medianas embarcaciones en la costa atl\u00e1ntica, permanecer en puerto, debido a vientos anormales y olas de 7 a 9 pies cerca de la costa, siendo superiores, mar a dentro. A causa de las lluvias, provocadas por una vaguada, el presidente Luis Abinader se reunir\u00e1 este s\u00e1bado en la sede del Centro de Operaciones de Emergencias (COE) con representantes de los organismos de emergencia para dar seguimiento a la situaci\u00f3n. El COE mantiene en alerta amarilla las provincias de Puerto Plata, Mar\u00eda Trinidad S\u00e1nchez, Espaillat, Hato Mayor, El Seibo, La Altagracia, Duarte, Saman\u00e1 y Hermanas Mirabal. Mientras que en alerta verde est\u00e1n Santo Domingo, Distrito Nacional, La Vega, Montecristi y Santiago. En ese sentido, se recomienda a las personas abstenerse de cruzar, r\u00edos, arroyos y ca\u00f1adas que presenten altos vol\u00famenes de agua en las provincias bajo alerta.EFE<\/p>\n","protected":false},"author":9,"featured_media":99992,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-99991","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/99991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=99991"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/99991\/revisions"}],"predecessor-version":[{"id":99993,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/99991\/revisions\/99993"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/99992"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=99991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=99991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=99991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}